{"id":71843,"date":"2023-11-09T18:00:00","date_gmt":"2023-11-09T14:30:00","guid":{"rendered":"https:\/\/pesterafsanjan.com\/blog\/?p=71843"},"modified":"2024-09-29T13:32:59","modified_gmt":"2024-09-29T10:02:59","slug":"%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%b2%d9%85%d8%a7%d9%86-%da%a9%d9%88%d8%af-%d9%85%d8%b1%d8%ba%db%8c-%d8%a8%d8%b1%d8%a7%db%8c-%d9%be%d8%b3%d8%aa%d9%87","status":"publish","type":"post","link":"https:\/\/pesterafsanjan.com\/blog\/%d8%a8%d9%87%d8%aa%d8%b1%db%8c%d9%86-%d8%b2%d9%85%d8%a7%d9%86-%da%a9%d9%88%d8%af-%d9%85%d8%b1%d8%ba%db%8c-%d8%a8%d8%b1%d8%a7%db%8c-%d9%be%d8%b3%d8%aa%d9%87","title":{"rendered":"\u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647"},"content":{"rendered":"\r\n<p><span style=\"font-weight: 400;\">\u0627\u0645\u0631\u0648\u0632\u0647 \u062f\u0631 \u0635\u0646\u0639\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc <\/span>\u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u06cc\u062f \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u200c\u0627\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc \u062c\u0632\u0621 \u06a9\u0648\u062f\u0647\u0627\u06cc \u0622\u0644\u06cc \u0648 \u063a\u06cc\u0631 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u062a\u063a\u0630\u06cc\u0647 \u062f\u0631\u062e\u062a\u0627\u0646\u060c \u06af\u06cc\u0627\u0647\u0627\u0646\u060c \u0627\u0635\u0644\u0627\u062d \u0648 \u062d\u0627\u0635\u0644\u062e\u06cc\u0632\u06cc \u062e\u0627\u06a9\u00a0\u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p>\u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0627\u0631\u0627 \u0628\u0648\u062f\u0646 \u0645\u0642\u062f\u0627\u0631 \u0632\u06cc\u0627\u062f \u0627\u0632\u062a\u060c \u0641\u0633\u0641\u0631 \u0648 \u067e\u062a\u0627\u0633\u06cc\u0645 \u062f\u0627\u0631\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0639\u0646\u0627\u0635\u0631 \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0627\u06cc\u0631 \u06a9\u0648\u062f\u0647\u0627\u06cc \u062f\u0627\u0645\u06cc \u0628\u0648\u062f\u0647 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f \u0648 \u062e\u0648\u0627\u0635 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0631\u062f.<\/p>\r\n\r\n\r\n\r\n<p>\u0628\u0627\u062a\u0648\u062c\u0647 \u0628\u0647 \u062e\u0648\u0627\u0635 \u0628\u0627\u0644\u0627\u06cc \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f \u062f\u0647\u06cc \u0628\u0647 \u062f\u0631\u062e\u062a\u0627\u0646 \u067e\u0633\u062a\u0647 \u0646\u06cc\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647\u200c\u0650\u06cc \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u062a\u0648\u0636\u06cc\u062d \u0628\u06cc\u0634\u062a\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u062e\u0648\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a.<\/p>\r\n\r\n\r\n\r\n<p>\u0628\u0631\u0627\u06cc \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0628\u0627\u06cc\u062f \u0622\u0646 \u0631\u0627 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f\u061b \u0627\u0645\u0627 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u06a9\u0648\u062f \u0645\u0631\u063a \u0628\u0631\u0627\u06cc \u067e\u0633\u062a\u0647 \u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u0627\u0633\u062a\u061f<\/p>\r\n\r\n\r\n\r\n<p>\u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0642\u0627\u0644\u0647 \u0628\u0627 \u0645\u0627 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0631\u0627 \u0628\u0647 \u062e\u0648\u0628\u06cc \u062f\u0631\u06a9 \u06a9\u0646\u06cc\u0645:<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><span style=\"color: #000000;\">\u0627\u0646\u0648\u0627\u0639 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc<\/span><\/h2>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/pesterafsanjan.com\/product-tag\/%DA%A9%D9%88%D8%AF-%D9%85%D8%B1%D8%BA%DB%8C\">\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc<\/a> \u0627\u0632 \u0645\u062f\u0641\u0648\u0639 \u0648 \u0627\u062f\u0631\u0627\u0631 \u0645\u0631\u063a \u0648 \u062c\u0648\u062c\u0647\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u062f\u0627\u062e\u0644 \u0645\u0631\u063a\u062f\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0628\u0647 \u062f\u0633\u062a \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f<\/span> \u0648 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u063a\u0646\u06cc \u0628\u0648\u062f\u0646 \u0627\u0632 \u0639\u0646\u0627\u0635\u0631 \u063a\u0630\u0627\u06cc\u06cc\u060c \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06a9\u0648\u062f \u062f\u0631 \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f.<\/p>\r\n\r\n\r\n\r\n<p>\u0627\u0646\u0648\u0627\u0639 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p>\r\n<blockquote>\r\n<p style=\"text-align: center;\">\u0628\u0631\u0627\u06cc <a href=\"https:\/\/pesterafsanjan.com\/product-tag\/%DA%A9%D9%88%D8%AF-%D9%85%D8%B1%D8%BA%DB%8C\">\u062e\u0631\u06cc\u062f \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc<\/a> \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><span style=\"color: #000000;\">\u0641\u0636\u0648\u0644\u0627\u062a \u062c\u0648\u062c\u0647\u200c\u0647\u0627\u06cc \u06af\u0648\u0634\u062a\u06cc<\/span><\/h3>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"770\" height=\"470\" class=\"wp-image-87959\" src=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u062c\u0648\u062c\u0647-\u0645\u0631\u063a\u06cc.jpg\" alt=\"\u062c\u0648\u062c\u0647 \u06af\u0648\u0634\u062a\u06cc\" srcset=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u062c\u0648\u062c\u0647-\u0645\u0631\u063a\u06cc.jpg 770w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u062c\u0648\u062c\u0647-\u0645\u0631\u063a\u06cc-300x183.jpg 300w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u062c\u0648\u062c\u0647-\u0645\u0631\u063a\u06cc-768x469.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>\r\n<figcaption class=\"wp-element-caption\">\u06a9\u0648\u062f \u062c\u0648\u062c\u0647 \u06af\u0648\u0634\u062a\u06cc<\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0646\u0648\u0639 \u06a9\u0648\u062f \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0627\u06cc\u0631 \u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0646\u06cc\u0631\u0648 (\u0627\u0646\u0631\u0698\u06cc) \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0627\u0633\u062a\u061b \u0632\u06cc\u0631\u0627 \u062f\u0627\u0631\u0627\u06cc \u0645\u0648\u0627\u062f \u0645\u063a\u0630\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0627\u0633\u062a \u0648 \u0628\u0627\u0639\u062b \u0634\u0627\u062f\u0627\u0628\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u06cc \u0634\u0648\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong>\u06a9\u0648\u062f \u0645\u0631\u063a\u200c\u0647\u0627\u06cc \u0645\u0627\u062f\u0631<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u06a9\u0648\u062f \u0627\u0632 \u0642\u0633\u0645\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u0631\u063a\u200c\u0647\u0627\u06cc \u062a\u062e\u0645\u200c\u06af\u0630\u0627\u0631 \u0631\u0627 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0628\u0647 \u062f\u0633\u062a \u0645\u06cc\u200c\u0622\u06cc\u062f<\/span> \u0648 <span style=\"font-weight: 400;\">\u062f\u0627\u0631\u0627\u06cc \u0645\u0642\u062f\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u067e\u0631\u0648\u062a\u0626\u06cc\u0646\u060c \u0645\u0646\u06af\u0646\u0632\u060c \u06a9\u0644\u0633\u06cc\u0645 \u0648 \u0641\u0633\u0641\u0631 \u0627\u0633\u062a \u0648 \u062f\u0631 \u0631\u0634\u062f \u0628\u0647\u062a\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u0648 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 <\/span>\u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0627\u0633\u062a.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><span style=\"color: #000000;\"><strong>\u06a9\u0648\u062f \u0646\u06cc\u0645\u0686\u0647\u200c\u0647\u0627\u06cc \u062a\u062e\u0645 \u06af\u0630\u0627\u0631<\/strong><\/span><\/h3>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0646\u0648\u0639 \u06a9\u0648\u062f \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u06cc\u0646 \u06a9\u0647 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0646\u06cc\u0645\u0686\u0647\u200c\u0647\u0627\u06cc \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u0634\u062f\u0647 \u062a\u062e\u0645 \u06af\u0630\u0627\u0631 \u0628\u0647 \u062f\u0633\u062a \u0645\u06cc\u200c\u0622\u06cc\u062f\u060c \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0627\u06cc\u0631 \u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc \u062f\u06cc\u06af\u0631 \u062f\u0627\u0631\u0627\u06cc \u0645\u0642\u062f\u0627\u0631 \u06a9\u0645\u062a\u0631\u06cc \u067e\u0631\u0648\u062a\u0626\u06cc\u0646 \u0648 \u0627\u0646\u0631\u0698\u06cc \u0627\u0633\u062a.<\/span><\/p>\r\n\r\n\r\n\r\n<p>\u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f\u060c \u062f\u0631 \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0646\u06cc\u0627\u0632 \u0632\u06cc\u0627\u062f\u06cc \u0628\u0647 \u0646\u06cc\u062a\u0631\u0648\u0698\u0646 \u0646\u062f\u0627\u0631\u0646\u062f\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<br \/><span style=\"font-weight: 400;\">\u062f\u0631 \u0648\u06cc\u062f\u06cc\u0648 \u0632\u06cc\u0631 \u0628\u0647 \u0635\u0648\u0631\u062a \u062e\u0644\u0627\u0635\u0647 \u062f\u0631 \u0645\u0648\u0631\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u06af\u0641\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a<\/span>.<\/p>\r\n\r\n<p><style>.h_iframe-aparat_embed_frame{position:relative;}.h_iframe-aparat_embed_frame .ratio{display:block;width:100%;height:auto;}.h_iframe-aparat_embed_frame iframe{position:absolute;top:0;left:0;width:100%;height:100%;}<\/style><\/p>\r\n<div class=\"h_iframe-aparat_embed_frame\"><iframe src=\"https:\/\/www.aparat.com\/video\/video\/embed\/videohash\/5yj9n\/vt\/frame\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u0641\u0648\u0627\u06cc\u062f \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647<\/h2>\r\n\r\n\r\n\r\n<p>\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0642\u062f\u0627\u0631 \u0646\u06cc\u062a\u0631\u0648\u0698\u0646 \u0628\u0627\u0644\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0627\u0631\u062f\u061b \u062f\u0627\u0631\u0627\u06cc \u0641\u0648\u0627\u06cc\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u0645\u062e\u0635\u0648\u0635\u0627\u064b \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0627\u0633\u062a.<\/p>\r\n\r\n\r\n\r\n<p>\u0627\u0632\u062c\u0645\u0644\u0647 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u062e\u0648\u0627\u0635 \u0622\u0646 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0627\u0631\u062f\u0647\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0627\u0633\u062a\u061b \u0627\u0645\u0627 \u0686\u06af\u0648\u0646\u0647\u061f<\/p>\r\n\r\n\r\n\r\n<p>\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0648\u0627\u062f\u0622\u0644\u06cc \u06a9\u0647 \u062f\u0627\u0631\u062f\u060c \u0633\u0628\u0628 \u0631\u0634\u062f \u0631\u0648\u06cc\u0634\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0634\u062f\u0647 \u0648 \u062f\u0631\u0646\u062a\u06cc\u062c\u0647 \u0631\u0634\u062f \u0631\u0648\u06cc\u0634\u06cc\u060c \u0634\u0627\u062e\u0647\u200c\u0647\u0627 \u0631\u0634\u062f \u0628\u0647\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0648 \u062a\u0648\u0644\u06cc\u062f \u062c\u0648\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0632\u0627\u06cc\u0634\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f\u061b \u0627\u0632\u0627\u06cc\u0646\u200c\u0631\u0648 \u062a\u0648\u0644\u06cc\u062f \u0645\u062d\u0635\u0648\u0644 \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\r\n\r\n\r\n\r\n<p>\u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0645\u0639\u0631\u0641\u06cc \u062f\u06cc\u06af\u0631 <a href=\"https:\/\/pesterafsanjan.com\/blog\/%D8%AA%D8%A7%D8%AB%DB%8C%D8%B1%D8%A7%D8%AA-%D9%88%DB%8C%DA%98%D9%87-%DA%A9%D9%88%D8%AF-%D9%85%D8%B1%D8%BA%DB%8C-%D8%AF%D8%B1-%DA%AF%DB%8C%D8%A7%D9%87%D8%A7%D9%86-%D9%88-%D8%AF%D8%B1%D8%AE%D8%AA%D8%A7\">\u0641\u0648\u0627\u06cc\u062f \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647<\/a> \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc <span style=\"font-weight: 400;\">\u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc\u06a9\u0631\u0648\u0628\u200c\u0647\u0627\u06cc \u0645\u0641\u06cc\u062f \u062e\u0627\u06a9 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li>\r\n\r\n\r\n\r\n<li><span style=\"font-weight: 400;\">\u0628\u0647 \u062f\u0644\u06cc\u0644 \u0648\u062c\u0648\u062f \u0645\u0642\u062f\u0627\u0631 \u0632\u06cc\u0627\u062f \u0627\u0632\u062a \u062f\u0631 \u0627\u06cc\u0646 \u0646\u0648\u0639 \u06a9\u0648\u062f \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0631\u0634\u062f \u062f\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li>\r\n\r\n\r\n\r\n<li>\u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647<span style=\"font-weight: 400;\"> \u0633\u0628\u0628 \u0631\u0634\u062f \u0628\u0631\u06af\u200c\u0647\u0627 \u0648 \u0633\u0628\u0632\u06cc\u0646\u06af\u06cc \u0622\u0646 <\/span>\u0645\u06cc\u200c\u0634\u0648\u062f.<\/li>\r\n\r\n\r\n\r\n<li><span style=\"font-weight: 400;\">\u062f\u0631 \u0635\u0648\u0631\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0639\u0646\u0627\u0635\u0631 \u063a\u0630\u0627\u06cc\u06cc \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 <\/span>\u062a\u0627\u0645\u06cc\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/li>\r\n\r\n\r\n\r\n<li><span style=\"font-weight: 400;\">\u0628\u0627\u0639\u062b \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u062f\u0641\u0627\u0639\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u06a9\u0648\u062f \u0645\u0631\u063a \u0628\u0631\u0627\u06cc \u067e\u0633\u062a\u0647<\/h2>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u062a\u0645\u0627\u0645 \u0641\u0635\u0648\u0644 \u0633\u0627\u0644 \u0627\u0645\u06a9\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a\u0627\u0646 \u0648 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f<\/span>.<\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0648 \u06af\u0631\u0641\u062a\u0646 \u0646\u062a\u06cc\u062c\u0647 \u0628\u0647\u062a\u0631 \u0641\u0635\u0644 \u0632\u0645\u0633\u062a\u0627\u0646 \u062f\u0631 \u0627\u0648\u0627\u062e\u0631 \u0627\u0633\u0641\u0646\u062f\u0645\u0627\u0647 \u0627\u0633\u062a<\/span> \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631 \u0627\u0628\u062a\u062f\u0627\u06cc \u0634\u0631\u0648\u0639 \u0631\u0634\u062f \u062f\u0631\u062e\u062a \u062f\u0631 \u0641\u0635\u0644 \u0628\u0647\u0627\u0631 \u0648 \u062f\u0631 \u0646\u0648\u0628\u062a \u0628\u0639\u062f\u06cc \u062f\u0631 \u0627\u0631\u062f\u06cc\u0628\u0647\u0634\u062a \u0645\u0627\u0647 \u0642\u0628\u0644 \u0627\u0632 \u06af\u0631\u0645 \u0634\u062f\u0646 \u0647\u0648\u0627 \u0642\u0627\u0628\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0633\u062a.<\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\"> \u0644\u0627\u0632\u0645 \u0628\u0647 \u0630\u06a9\u0631 \u0627\u0633\u062a\u060c \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u062f\u0631 \u0641\u0635\u0644 \u062a\u0627\u0628\u0633\u062a\u0627\u0646 \u0648 \u062f\u0631 \u0631\u0648\u0632\u0647\u0627\u06cc \u06af\u0631\u0645 \u0646\u0628\u0627\u06cc\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u06a9\u0646\u06cc\u062f\u061b \u0632\u06cc\u0631\u0627 \u0628\u0627\u0639\u062b \u062e\u0633\u0627\u0631\u062a \u0628\u0647 \u0645\u062d\u0635\u0648\u0644 \u0648 \u062f\u0631\u062e\u062a <\/span>\u067e\u0633\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"770\" height=\"470\" class=\"wp-image-87962\" src=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u0628\u0631\u0627\u06cc-\u067e\u0633\u062a\u0647-\u0628\u0633\u06cc\u0627\u0631-\u0645\u0641\u06cc\u062f-\u0627\u0633\u062a.jpg\" alt=\"\u06a9\u0648\u062f \u0645\u0627\u06cc\u0639 \u0645\u0631\u063a\u06cc\" srcset=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u0628\u0631\u0627\u06cc-\u067e\u0633\u062a\u0647-\u0628\u0633\u06cc\u0627\u0631-\u0645\u0641\u06cc\u062f-\u0627\u0633\u062a.jpg 770w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u0628\u0631\u0627\u06cc-\u067e\u0633\u062a\u0647-\u0628\u0633\u06cc\u0627\u0631-\u0645\u0641\u06cc\u062f-\u0627\u0633\u062a-300x183.jpg 300w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u0628\u0631\u0627\u06cc-\u067e\u0633\u062a\u0647-\u0628\u0633\u06cc\u0627\u0631-\u0645\u0641\u06cc\u062f-\u0627\u0633\u062a-768x469.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>\r\n<figcaption class=\"wp-element-caption\">\u06a9\u0648\u062f \u0645\u0627\u06cc\u0639 \u0645\u0631\u063a\u06cc \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u0648\u062f\u0647\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0627\u0633\u062a.<\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">\u0632\u0645\u0627\u0646 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0645\u0627\u06cc\u0639<\/h3>\r\n\r\n\r\n\r\n<p>\u0632\u0645\u0627\u0646 \u0645\u0635\u0631\u0641 <a href=\"https:\/\/pesterafsanjan.com\/blog\/%da%a9%d9%88%d8%af-%d9%85%d8%a7%db%8c%d8%b9-%d9%85%d8%b1%d8%ba%db%8c-%da%86%db%8c%d8%b3%d8%aa\">\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0627\u06cc\u0639<\/a> \u0627\u0632 \u0627\u0628\u062a\u062f\u0627\u06cc \u0641\u0635\u0644 \u0631\u0634\u062f \u062a\u0627 \u0632\u0645\u0627\u0646 \u0628\u0631\u062f\u0627\u0634\u062a \u0627\u0633\u062a.<\/p>\r\n\r\n\r\n\r\n<p>\u06a9\u0648\u062f \u0645\u0627\u06cc\u0639 \u0645\u0631\u063a\u06cc \u0641\u0648\u0627\u06cc\u062f \u0628\u06cc\u200c\u0634\u0645\u0627\u0631\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0632\u06cc\u0631 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0648\u0631\u062f\u06cc \u0628\u06cc\u0627\u0646 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>\u0645\u0642\u062f\u0627\u0631 \u0645\u0635\u0631\u0641 \u06a9\u0645\u062a\u0631 \u0646\u0633\u0628\u062a \u0628\u0647 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u062e\u0627\u0645<\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pesterafsanjan.com\/product\/%DA%A9%D9%88%D8%AF-%D9%85%D8%A7%DB%8C%D8%B9-%D9%85%D8%B1%D8%BA%DB%8C-%D8%A8%DB%8C%D9%88%D8%A7%DA%AF%D8%B1%DB%8C\">\u06a9\u0648\u062f \u0645\u0627\u06cc\u0639 \u0645\u0631\u063a\u06cc<\/a> \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627<\/li>\r\n\r\n\r\n\r\n<li>\u0631\u0627\u062d\u062a\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647<\/li>\r\n\r\n\r\n\r\n<li>\u063a\u0646\u06cc\u200c\u062a\u0631 \u0628\u0648\u062f\u0646 \u0646\u0633\u0628\u062a \u0628\u0647 \u06a9\u0648\u062f \u062e\u0627\u0645(\u063a\u0646\u06cc \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u062a\u0648\u0644\u06cc\u062f\u200c\u06a9\u0646\u0646\u062f\u0647)<\/li>\r\n\r\n\r\n\r\n<li>\u0622\u0644\u0648\u062f\u06af\u06cc \u06a9\u0645\u062a\u0631<\/li>\r\n\r\n\r\n\r\n<li>\u062c\u0630\u0628 \u0628\u0627\u0644\u0627\u062a\u0631 \u0646\u0633\u0628\u062a \u0628\u0647 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u062c\u0627\u0645\u062f<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u0645\u0642\u062f\u0627\u0631 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647<\/h2>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u0648\u0639 \u0628\u0627\u0641\u062a \u062e\u0627\u06a9\u060c \u0645\u06cc\u0632\u0627\u0646 \u0628\u0627\u0631\u0646\u062f\u06af\u06cc\u060c \u0645\u0627\u062f\u0647 \u0622\u0644\u06cc \u062e\u0627\u06a9\u060c \u0646\u06cc\u0627\u0632 \u06af\u06cc\u0627\u0647 \u0648 \u0641\u0635\u0644 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 <a href=\"https:\/\/pesterafsanjan.com\/blog\/%D9%85%D9%82%D8%AF%D8%A7%D8%B1-%D9%85%D8%B5%D8%B1%D9%81-%DA%A9%D9%88%D8%AF-%D9%85%D8%B1%D8%BA%DB%8C\">\u0645\u0642\u062f\u0627\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc<\/a> \u0628\u0631\u0627\u06cc <\/span>\u0647\u0631 \u0646\u0648\u0639 \u062f\u0631\u062e\u062a \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a.<\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0645\u062b\u0627\u0644 \u0645\u0642\u062f\u0627\u0631 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u062f\u0631 \u0647\u0631 \u0647\u06a9\u062a\u0627\u0631 \u062d\u062f\u0627\u06a9\u062b\u0631 10 \u062a\u0627 20 \u062a\u0646 (\u062f\u0631 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u0622\u0628 \u0648 \u062e\u0627\u06a9) \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u061b \u0627\u0645\u0627 \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u06af\u0631 \u0628\u0647 \u0635\u0648\u0631\u062a \u062e\u0648\u062f\u0633\u0631\u0627\u0646\u0647 \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f\u060c \u0628\u0647 \u0646\u062a\u06cc\u062c\u0647 \u062f\u0644\u062e\u0648\u0627\u0647 \u062e\u0648\u062f \u0646\u062e\u0648\u0627\u0647\u06cc\u062f \u0631\u0633\u06cc\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p>\u0645\u0642\u062f\u0627\u0631 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u06cc\u06af\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u0648 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a\u061b \u0645\u062b\u0644\u0627\u064b \u0686\u0648\u0646 \u0632\u0639\u0641\u0631\u0627\u0646 \u0646\u0633\u0628\u062a \u0628\u0647 \u062f\u06cc\u06af\u0631 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0631\u0634\u062f \u0631\u0648\u06cc\u0634\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0646\u062f\u0627\u0631\u062f\u060c \u0628\u0627\u06cc\u062f \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u06a9\u0645\u062a\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n<p>\u0644\u0627\u0632\u0645 \u0628\u0647 \u0630\u06a9\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0642\u062f\u0627\u0631 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0627\u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0647\u0631 \u062f\u0631\u062e\u062a \u0648 \u06af\u06cc\u0627\u0647 \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a \u0648 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u067e\u06cc\u0634 \u0627\u0632 \u06a9\u0648\u062f \u062f\u0647\u06cc \u0628\u0627 \u0645\u062a\u062e\u0635\u0635 \u06a9\u0648\u062f \u0648 \u0633\u0645 \u0645\u0634\u0648\u0631\u062a \u06a9\u0646\u06cc\u062f.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc<\/h2>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 2 \u0631\u0648\u0634 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\"><strong>\u0631\u0648\u0634 \u0686\u0627\u0644\u06a9\u0648\u062f<\/strong><\/span><\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u200c\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f \u062f\u0647\u06cc \u062f\u0631\u062e\u062a\u0627\u0646 \u067e\u0633\u062a\u0647 \u0648 \u0633\u0627\u06cc\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc \u0634\u0648\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0628\u0647 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a \u06a9\u0647 \u06cc\u06a9 \u06af\u0648\u062f\u0627\u0644 \u06a9\u0646\u0627\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u062d\u0641\u0631 \u06a9\u0631\u062f\u0647 \u0648 \u0645\u0642\u062f\u0627\u0631 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0631\u0627 \u062f\u0627\u062e\u0644 \u0622\u0646 \u0631\u06cc\u062e\u062a\u0647 \u0648 \u0633\u067e\u0633 \u0628\u0631\u0627\u06cc \u062c\u0630\u0628 \u0628\u0647\u062a\u0631 \u06a9\u0648\u062f\u0647\u0627 \u062a\u0648\u0633\u0637 \u062f\u0631\u062e\u062a\u0627\u0646 \u0645\u062d\u0644 \u0686\u0627\u0644\u06a9\u0648\u062f \u0631\u0627 \u0622\u0628\u06cc\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\"><strong>\u0631\u0648\u0634 \u067e\u062e\u0634 \u0633\u0637\u062d\u06cc<\/strong><\/span><\/p>\r\n\r\n\r\n\r\n<p>\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0631\u0627 \u0628\u0647 \u0631\u0648\u0634 \u067e\u062e\u0634 \u0633\u0637\u062d\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0627\u0646\u062c\u0627\u0645 \u06a9\u0648\u062f \u062f\u0647\u06cc \u0628\u0647 \u0635\u0648\u0631\u062a \u067e\u062e\u0634 \u0633\u0637\u062d\u06cc \u0631\u0648\u0634\u06cc \u0622\u0633\u0627\u0646 \u0648 \u06a9\u0645\u200c\u0647\u0632\u06cc\u0646\u0647 \u0627\u0633\u062a.<\/span><\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u06a9\u0648\u062f \u0631\u0627 \u0631\u0648\u06cc \u0632\u0645\u06cc\u0646 \u062f\u0631 \u0645\u062d\u0644 \u0633\u0627\u06cc\u0647 \u0627\u0646\u062f\u0627\u0632 \u067e\u0647\u0646 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0627 \u062e\u0627\u06a9 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0646\u06cc\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"770\" height=\"470\" class=\"wp-image-87965\" src=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u062c\u0627\u0645\u062f.jpg\" alt=\"\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u062c\u0627\u0645\u062f\" srcset=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u062c\u0627\u0645\u062f.jpg 770w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u062c\u0627\u0645\u062f-300x183.jpg 300w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u062c\u0627\u0645\u062f-768x469.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>\r\n<figcaption class=\"wp-element-caption\">\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u062c\u0627\u0645\u062f<\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u0634\u06cc\u0631\u0627\u0628\u0647 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u067e\u0633\u062a\u0647<\/h2>\r\n\r\n\r\n\r\n<p>\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u062e\u0648\u062f \u0628\u0647 \u0635\u0648\u0631\u062a \u062c\u0627\u0645\u062f \u0627\u0633\u062a\u061b \u0627\u0645\u0627 \u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0622\u0646 \u0634\u06cc\u0631\u0627\u0628\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f \u0648 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc \u062f\u0631 \u0628\u0627\u063a\u0627\u062a \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p class=\"has-text-align-center\"><strong> \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646\u06a9\u0647 \u0628\u0631\u0627\u06cc \u0634\u06cc\u0631\u0627\u0628\u0647 \u06af\u06cc\u0631\u06cc\u060c \u06a9\u0648\u062f \u062e\u0627\u0645 \u06a9\u0645\u062a\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0645\u0635\u0631\u0641 \u0622\u0646 \u0628\u0647\u200c\u062c\u0627\u06cc \u0646\u0648\u0639 \u062c\u0627\u0645\u062f \u0648 \u062e\u0627\u0645 \u0622\u0646 \u0633\u0628\u0628 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/strong><\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u0645\u0636\u0631\u0627\u062a \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc<\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><span style=\"font-weight: 400;\">\u0647\u062c\u0648\u0645 \u067e\u0634\u0647 \u0648 \u0645\u06af\u0633 \u062f\u0631 \u0645\u0632\u0627\u0631\u0639\u00a0<\/span><\/li>\r\n\r\n\r\n\r\n<li>\u0627\u0645\u06a9\u0627\u0646 \u0622\u0633\u06cc\u0628\u200c\u062f\u06cc\u062f\u0646 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0648 \u062f\u0631\u062e\u062a\u0627\u0646 \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u06cc \u0631\u0648\u06cc\u0647<\/li>\r\n\r\n\r\n\r\n<li>\u0622\u0628\u0634\u0648\u06cc\u06cc \u0633\u0631\u06cc\u0639 \u062f\u0631 \u0635\u0648\u0631\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0627\u062f\u0631\u0633\u062a<\/li>\r\n\r\n\r\n\r\n<li>\u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u0622\u0628 \u0648 \u062e\u0627\u06a9 \u0634\u0648\u0631<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u0634\u0631\u0627\u06cc\u0637 \u0648 \u0646\u062d\u0648\u0647 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc<\/h2>\r\n\r\n\r\n\r\n<p>\u0628\u0627\u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u062a\u0628\u062f\u06cc\u0644 \u0627\u0632\u062a \u0628\u0647 \u06af\u0627\u0632 \u0622\u0645\u0648\u0646\u06cc\u0627\u06a9 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u062c\u0627\u062f \u0628\u0648\u06cc \u062a\u0646\u062f \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u062f\u0631 \u0641\u0636\u0627\u06cc \u0628\u0627\u0632 \u0628\u0647 \u062d\u0627\u0644 \u062e\u0648\u062f \u0631\u0647\u0627 \u0646\u0634\u0648\u062f \u0648 \u06cc\u0627 \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u062f\u0631 \u0628\u0627\u063a \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u062f.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u0686\u0647 \u062f\u0631\u062e\u062a\u0627\u0646\u06cc \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a\u061f<\/h2>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u062f\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u062d\u0635\u0648\u0644 \u062f\u0647\u06cc \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u06cc\u0648\u0647 \u062f\u0631\u062e\u062a\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p><strong>\u06af\u0631\u062f\u0648:<\/strong>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a\u0627\u0646 \u06af\u0631\u062f\u0648 \u0645\u0641\u06cc\u062f \u0627\u0633\u062a \u0648 <span style=\"font-weight: 400;\">\u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0627\u0631\u0627 \u0628\u0648\u062f\u0646 \u0645\u0642\u062f\u0627\u0631 \u0628\u0627\u0644\u0627\u06cc \u0627\u0632\u062a\u060c \u0641\u0633\u0641\u0631 \u0648 \u067e\u062a\u0627\u0633 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u062d\u0635\u0648\u0644 \u062f\u0647\u06cc \u06af\u0631\u062f\u0648 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a\u0627\u0646 <a href=\"https:\/\/pesterafsanjan.com\/blog\/tag\/%da%af%d8%b1%d8%af%d9%88\">\u06af\u0631\u062f\u0648<\/a> \u0627\u0648\u0627\u062e\u0631 \u0628\u0647\u0627\u0631\u060c \u0627\u0648\u0627\u062e\u0631 \u062a\u0627\u0628\u0633\u062a\u0627\u0646\u060c \u0627\u0648\u0627\u062e\u0631 \u0632\u0645\u0633\u062a\u0627\u0646 \u0648 \u06cc\u0627 \u0627\u0648\u0627\u06cc\u0644 \u0628\u0647\u0627\u0631 \u0627\u0633\u062a. <\/span><\/p>\r\n\r\n\r\n\r\n<p><strong>\u0645\u0631\u06a9\u0628\u0627\u062a: <\/strong><span style=\"font-weight: 400;\">\u0632\u0645\u0627\u0646 \u0645\u0635\u0631\u0641 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0628\u0631\u0627\u06cc \u0645\u0631\u06a9\u0628\u0627\u062a \u062f\u0631 \u0641\u0635\u0644 \u0631\u0634\u062f \u0622\u0646\u200c\u0647\u0627 \u0627\u0633\u062a. \u0628\u0647 \u0627\u06cc\u0646 \u0634\u06a9\u0644 \u06a9\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0645\u0646\u0627\u0633\u0628\u06cc \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0631\u0627 \u0628\u0631 \u0631\u0648\u06cc \u0633\u0637\u062d \u062e\u0627\u06a9 \u0631\u06cc\u062e\u062a\u0647 \u0648 \u0628\u0627 \u0627\u062d\u062a\u06cc\u0627\u0637 \u0628\u0627 \u062e\u0627\u06a9 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0646\u06cc\u062f<\/span> \u0648 \u06cc\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u0632 \u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc \u0645\u0627\u06cc\u0639 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u0622\u0628\u06cc\u0627\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center\"><strong>\u0628\u0647 \u0645\u0642\u0627\u0644\u0647 <a href=\"https:\/\/pesterafsanjan.com\/blog\/%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86-%D8%B2%D9%85%D8%A7%D9%86-%DA%A9%D8%A7%D8%B4%D8%AA-%D9%86%D9%87%D8%A7%D9%84-%D9%85%D8%B1%DA%A9%D8%A8%D8%A7%D8%AA\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u06a9\u0627\u0634\u062a \u0646\u0647\u0627\u0644 \u0645\u0631\u06a9\u0628\u0627\u062a<\/a> \u0633\u0631 \u0628\u0632\u0646\u06cc\u062f.<\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong>\u0632\u0639\u0641\u0631\u0627\u0646: <\/strong><span style=\"font-weight: 400;\">\u0632\u0645\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u0632\u0639\u0641\u0631\u0627\u0646\u060c \u067e\u0633 \u0627\u0632 \u0633\u0628\u0632 \u0634\u062f\u0646 \u0632\u0639\u0641\u0631\u0627\u0646 \u0647\u0627 \u0628\u0647 \u0631\u0648\u0634 \u0633\u0631\u06a9 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u062a\u0627\u0645\u06cc\u0646 \u06a9\u0631\u062f\u0646 \u0645\u0648\u0627\u062f \u0645\u063a\u0630\u06cc \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u0632\u0627\u0646 \u06af\u0644\u062f\u0647\u06cc \u0632\u0639\u0641\u0631\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p><strong>\u0632\u0631\u062f\u0622\u0644\u0648: <\/strong><span style=\"font-weight: 400;\">\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u0632\u0631\u062f\u0622\u0644\u0648 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 <span style=\"font-weight: 400;\">\u0645\u062d\u0635\u0648\u0644 \u062f\u0647\u06cc<\/span><\/span>\u060c <span style=\"font-weight: 400;\">\u0633\u0627\u06cc\u0632 \u0645\u06cc\u0648\u0647 \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc\u200c\u0634\u0648\u062f<\/span> \u0648 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u0641\u0635\u0644 \u0631\u0634\u062f \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0631\u062e\u062a\u0627\u0646 \u062f\u0627\u062f\u0647 \u0634\u0648\u062f.<\/p>\r\n\r\n\r\n\r\n<p><strong>\u063a\u0644\u0627\u062a \u0648 \u06af\u0646\u062f\u0645: <\/strong><span style=\"font-weight: 400;\">\u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u062f\u0631 \u0632\u0645\u0627\u0646 \u0633\u0627\u0642\u0647 \u062f\u0647\u06cc\u060c \u067e\u0646\u062c\u0647 \u0632\u0646\u06cc \u0648 \u0632\u0645\u0627\u0646 \u067e\u0631 \u0634\u062f\u0646 \u062e\u0648\u0634\u0647\u200c\u0647\u0627 \u0628\u0647 \u06af\u06cc\u0627\u0647 \u062f\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p><span style=\"font-weight: 400;\"> \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0631\u0627 \u0647\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0635\u0648\u0631\u062a \u0622\u0628\u06cc \u0648 \u0647\u0645 \u0628\u0647 \u0635\u0648\u0631\u062a \u062f\u06cc\u0645\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u062a\u0646\u0627\u0698 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<p><strong>\u062f\u0631\u062e\u062a \u0633\u06cc\u0628:<\/strong><span style=\"font-weight: 400;\"> \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a\u0627\u0646 \u0633\u06cc\u0628 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a\u060c \u062f\u0631 \u0641\u0635\u0644 \u0631\u0634\u062f \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u06a9\u0648\u062f \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0642\u0627\u0648\u0645\u062a \u062f\u0631\u062e\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u062a\u0646\u0634\u200c\u0647\u0627 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u06cc\u0631\u06cc\u0646\u06cc\u060c \u0628\u0627\u0632\u0627\u0631\u067e\u0633\u0646\u062f\u06cc \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u06cc\u0648\u0647\u200c\u0647\u0627\u06cc \u0633\u06cc\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"770\" height=\"470\" class=\"wp-image-87967\" src=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u0628\u0631\u0627\u06cc-\u062f\u0631\u062e\u062a-\u0633\u06cc\u0628.jpg\" alt=\"\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u0633\u06cc\u0628\" srcset=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u0628\u0631\u0627\u06cc-\u062f\u0631\u062e\u062a-\u0633\u06cc\u0628.jpg 770w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u0628\u0631\u0627\u06cc-\u062f\u0631\u062e\u062a-\u0633\u06cc\u0628-300x183.jpg 300w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2023\/11\/\u06a9\u0648\u062f-\u0645\u0631\u063a\u06cc-\u0628\u0631\u0627\u06cc-\u062f\u0631\u062e\u062a-\u0633\u06cc\u0628-768x469.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>\r\n<figcaption class=\"wp-element-caption\">\u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0633\u0628\u0628 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u06cc\u0648\u0647 \u062f\u0631 \u062f\u0631\u062e\u062a \u0633\u06cc\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u06a9\u0644\u0627\u0645 \u0622\u062e\u0631<\/h2>\r\n\r\n\r\n\r\n<p>\u062f\u0631 \u067e\u0633\u062a\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0628\u0631\u0627\u06cc \u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u062f\u0631 \u0627\u0628\u062a\u062f\u0627\u06cc \u0641\u0635\u0644 \u0631\u0634\u062f (\u0627\u0633\u0641\u0646\u062f\u0645\u0627\u0647 \u062a\u0627 \u0645\u0647\u0631\u0645\u0627\u0647) \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0622\u0628 \u0627\u0633\u062a\u0627\u0631\u062a \u0627\u0633\u062a \u06a9\u0647 \u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u0646\u0648\u0639 \u0648 \u0646\u06cc\u0627\u0632 \u06af\u06cc\u0627\u0647\u060c \u0634\u0631\u0627\u06cc\u0637 \u0622\u0628 \u0648 \u0647\u0648\u0627\u06cc\u06cc \u0648&#8230; \u0627\u06cc\u0646 \u062a\u0639\u06cc\u06cc\u0646 \u0632\u0645\u0627\u0646\u06cc \u062a\u063a\u06cc\u06cc\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\r\n\r\n\r\n\r\n<p>\u0645\u0635\u0631\u0641 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u062e\u062a \u067e\u0633\u062a\u0647 \u0633\u0628\u0628 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0627\u0631\u062f\u0647\u06cc \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644 \u0627\u06cc\u0646 \u062f\u0631\u062e\u062a \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\r\n\r\n\r\n\r\n<p>\u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0645\u0627\u06cc\u0639 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f\u061b \u0632\u06cc\u0631\u0627 \u062c\u0630\u0628 \u0628\u0627\u0644\u0627\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0646\u0648\u0639 \u062c\u0627\u0645\u062f \u0622\u0646 \u062f\u0627\u0631\u062f.<\/p>\r\n\r\n\r\n\r\n<p>\u0627\u0632 \u06a9\u0648\u062f \u0645\u0631\u063a\u06cc \u0645\u0627\u06cc\u0639 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f \u062f\u0647\u06cc \u0628\u0647 \u0633\u0627\u06cc\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u0648 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\r\n\r\n\r\n\r\n<p>\u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u06cc\u0645 \u0627\u0632 \u062e\u0648\u0627\u0646\u062f\u0646 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0644\u0630\u062a \u0628\u0631\u062f\u0647 \u0628\u0627\u0634\u06cc\u062f. \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc <a href=\"https:\/\/pesterafsanjan.com\/product-category\/%D8%AE%D8%B1%DB%8C%D8%AF-%DA%A9%D9%88%D8%AF\">\u062e\u0631\u06cc\u062f \u06a9\u0648\u062f<\/a> \u0628\u0647 \u0635\u0641\u062d\u0647 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0645\u0627 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center\"><div style=\"display: flex; justify-content:center; flex-wrap:wrap; border-bottom:1px solid #f7f7f7; border-left:1px solid #f7f7f7; margin-bottom:20px\"><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/800\/\u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc-12_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc 25 \u06a9\u06cc\u0644\u0648\u06cc\u06cc\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc 25 \u06a9\u06cc\u0644\u0648\u06cc\u06cc<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">4,700,000 \u062a\u0648\u0645\u0627\u0646<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f-\u067e\u0633\u062a\u0647\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/716\/1 (7)_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc \u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f \u067e\u0633\u062a\u0647 20 \u0644\u06cc\u062a\u0631\u06cc\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f-\u067e\u0633\u062a\u0647\">\u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc \u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f \u067e\u0633\u062a\u0647 20 \u0644\u06cc\u062a\u0631\u06cc<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f-\u067e\u0633\u062a\u0647\"><span style=\"text-decoration:line-through; color: red; margin-right:10px;\">3,700,000 \u062a\u0648\u0645\u0627\u0646<\/span><span style=\"margin-left:5px;\">3,500,000 \u062a\u0648\u0645\u0627\u0646<\/span><\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/753\/\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc-1_350x350.webp\" alt=\"\u06a9\u0648\u062f \u0647\u06cc\u0648\u0645\u06cc\u06a9 \u0627\u0633\u06cc\u062f \u0645\u0627\u06cc\u0639 \u0628\u06cc\u0648 \u0627\u06af\u0631\u06cc 20 \u0644\u06cc\u062a\u0631\u06cc\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u0647\u06cc\u0648\u0645\u06cc\u06a9 \u0627\u0633\u06cc\u062f \u0645\u0627\u06cc\u0639 \u0628\u06cc\u0648 \u0627\u06af\u0631\u06cc 20 \u0644\u06cc\u062a\u0631\u06cc<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/799\/544_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc 20 \u0644\u06cc\u062a\u0631\u06cc (\u06af\u0648\u06af\u0631\u062f \u0645\u0627\u06cc\u0639 \u06a9\u0644\u0633\u06cc\u0645\u06cc)\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc 20 \u0644\u06cc\u062a\u0631\u06cc (\u06af\u0648\u06af\u0631\u062f \u0645\u0627\u06cc\u0639 \u06a9\u0644\u0633\u06cc\u0645\u06cc)<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">1,950,000 \u062a\u0648\u0645\u0627\u0646<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0645\u06cc\u06a9\u0631\u0648-\u0645\u06cc\u06a9\u0633-\u067e\u0648\u062f\u0631\u06cc-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/798\/\u0645\u06cc\u06a9\u0631\u0648\u0645\u06cc\u06a9\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc12_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0645\u06cc\u06a9\u0631\u0648\u0645\u06cc\u06a9\u0633 \u067e\u0648\u062f\u0631\u06cc \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0645\u06cc\u06a9\u0631\u0648-\u0645\u06cc\u06a9\u0633-\u067e\u0648\u062f\u0631\u06cc-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u0645\u06cc\u06a9\u0631\u0648\u0645\u06cc\u06a9\u0633 \u067e\u0648\u062f\u0631\u06cc \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0645\u06cc\u06a9\u0631\u0648-\u0645\u06cc\u06a9\u0633-\u067e\u0648\u062f\u0631\u06cc-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0645\u06cc\u06a9\u0631\u0648-\u0645\u06cc\u06a9\u0633-\u067e\u0648\u062f\u0631\u06cc-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f-\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0642\u0627\u0631\u0686-\u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/818\/\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f-\u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f_350x350.jpg\" alt=\"\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f \u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc (\u0642\u0627\u0631\u0686 \u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627)\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f-\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0642\u0627\u0631\u0686-\u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627\">\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f \u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc (\u0642\u0627\u0631\u0686 \u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627)<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f-\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0642\u0627\u0631\u0686-\u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627\">200,000 \u062a\u0648\u0645\u0627\u0646<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9\u0644\u0633\u06cc\u0645\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/45\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9-1\u0644\u0633\u06cc\u0645_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0646\u06cc\u062a\u0631\u0627\u062a \u06a9\u0644\u0633\u06cc\u0645\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9\u0644\u0633\u06cc\u0645\">\u06a9\u0648\u062f \u0646\u06cc\u062a\u0631\u0627\u062a \u06a9\u0644\u0633\u06cc\u0645<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9\u0644\u0633\u06cc\u0645\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9\u0644\u0633\u06cc\u0645\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0647\u0648\u06a9\u0631\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/37\/\u0647\u0648\u06a9\u0631-1_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc \u0647\u0648\u06a9\u0631\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0647\u0648\u06a9\u0631\">\u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc \u0647\u0648\u06a9\u0631<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0647\u0648\u06a9\u0631\">1,000,000 \u062a\u0648\u0645\u0627\u0646<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06af\u0648\u06af\u0631\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/634\/987465132_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u06af\u0648\u06af\u0631\u062f \u0645\u0627\u06cc\u0639 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06af\u0648\u06af\u0631\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u06af\u0648\u06af\u0631\u062f \u0645\u0627\u06cc\u0639 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06af\u0648\u06af\u0631\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06af\u0648\u06af\u0631\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-\u0633\u0627\u0632\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/743\/\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-11_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0633\u0648\u0644\u0641\u0627\u062a \u0622\u0647\u0646 \u06a9\u0646\u062c\u0627\u0644\u0647 \u0633\u0627\u0632\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-\u0633\u0627\u0632\">\u06a9\u0648\u062f \u0633\u0648\u0644\u0641\u0627\u062a \u0622\u0647\u0646 \u06a9\u0646\u062c\u0627\u0644\u0647 \u0633\u0627\u0632<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-\u0633\u0627\u0632\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-\u0633\u0627\u0632\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u06a9\u0644\u0627\u062a-\u0622\u0647\u0646-6-\u0631\u0648\u06cc\u0634\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/594\/1-(225)_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u06a9\u0644\u0627\u062a \u0622\u0647\u0646 (6%) \u0631\u0648\u06cc\u0634\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u06a9\u0644\u0627\u062a-\u0622\u0647\u0646-6-\u0631\u0648\u06cc\u0634\">\u06a9\u0648\u062f \u06a9\u0644\u0627\u062a \u0622\u0647\u0646 (6%) \u0631\u0648\u06cc\u0634<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u06a9\u0644\u0627\u062a-\u0622\u0647\u0646-6-\u0631\u0648\u06cc\u0634\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u06a9\u0644\u0627\u062a-\u0622\u0647\u0646-6-\u0631\u0648\u06cc\u0634\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/702\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc2_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0641\u0633\u0641\u06cc\u062a \u067e\u062a\u0627\u0633\u06cc\u0645 \u0641\u0648\u06af\u0627\u0631\u062f \u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\">\u06a9\u0648\u062f \u0641\u0633\u0641\u06cc\u062a \u067e\u062a\u0627\u0633\u06cc\u0645 \u0641\u0648\u06af\u0627\u0631\u062f \u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\">09916924189<\/a><\/div><\/div><a href=\"https:\/\/pesterafsanjan.com\/shop\" style=\"display:block; text-align:center; background-color:#9C27B0; color: #fff; padding:10px; font-size:15px; font-family:IRANSansWeb_Light; margin:30px 0;\">\u0645\u0634\u0627\u0647\u062f\u0647 \u062a\u0645\u0627\u0645\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0641\u0631\u0648\u0634\u06af\u0627\u0647<\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0645\u0631\u0648\u0632\u0647 \u062f\u0631 \u0635\u0646\u0639\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u0641\u06cc\u062f \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u200c\u0627\u0646\u062f. \u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc \u062c\u0632\u0621 \u06a9\u0648\u062f\u0647\u0627\u06cc \u0622\u0644\u06cc \u0648 \u063a\u06cc\u0631 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u062a\u063a\u0630\u06cc\u0647 \u062f\u0631\u062e\u062a\u0627\u0646\u060c \u06af\u06cc\u0627\u0647\u0627\u0646\u060c \u0627\u0635\u0644\u0627\u062d \u0648 \u062d\u0627\u0635\u0644\u062e\u06cc\u0632\u06cc \u062e\u0627\u06a9\u00a0\u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f. \u06a9\u0648\u062f\u0647\u0627\u06cc \u0645\u0631\u063a\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0627\u0631\u0627 \u0628\u0648\u062f\u0646 \u0645\u0642\u062f\u0627\u0631 \u0632\u06cc\u0627\u062f \u0627\u0632\u062a\u060c \u0641\u0633\u0641\u0631 \u0648 \u067e\u062a\u0627\u0633\u06cc\u0645 \u062f\u0627\u0631\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0639\u0646\u0627\u0635\u0631 \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0627\u06cc\u0631 \u06a9\u0648\u062f\u0647\u0627\u06cc \u062f\u0627\u0645\u06cc \u0628\u0648\u062f\u0647 \u0648 [&hellip;]<\/p>\n","protected":false},"author":1234,"featured_media":87972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24663,3360],"tags":[24937,24760,24761],"class_list":["post-71843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-24663","category-3360","tag-24937","tag-24760","tag-24761"],"acf":[],"_links":{"self":[{"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/posts\/71843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/users\/1234"}],"replies":[{"embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/comments?post=71843"}],"version-history":[{"count":1,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/posts\/71843\/revisions"}],"predecessor-version":[{"id":91933,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/posts\/71843\/revisions\/91933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/media\/87972"}],"wp:attachment":[{"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/media?parent=71843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/categories?post=71843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/tags?post=71843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}