{"id":10671,"date":"2023-04-11T09:31:00","date_gmt":"2023-04-11T05:01:00","guid":{"rendered":"http:\/\/pesterafsanjan.com\/?p=10671"},"modified":"2025-03-30T11:53:51","modified_gmt":"2025-03-30T07:23:51","slug":"%d8%b3%d8%b1%d8%ae%d8%b1%d8%b7%d9%88%d9%85%db%8c-%d9%be%d8%b3%d8%aa%d9%87","status":"publish","type":"post","link":"https:\/\/pesterafsanjan.com\/blog\/%d8%b3%d8%b1%d8%ae%d8%b1%d8%b7%d9%88%d9%85%db%8c-%d9%be%d8%b3%d8%aa%d9%87","title":{"rendered":"\u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647 \u0648 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0622\u0646"},"content":{"rendered":"\n<p>\u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc\u060c \u0647\u0645\u0627\u0646\u200c\u0637\u0648\u0631 \u06a9\u0647 \u0627\u0632 \u0627\u0633\u0645\u0634 \u067e\u06cc\u062f\u0627\u0633\u062a \u062d\u0634\u0631\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u062d\u0645\u0644\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06af\u0633\u062a\u0631\u0647\u200c\u06cc \u0628\u0632\u0631\u06af\u06cc \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0631\u0627 \u0645\u0648\u0631\u062f \u0647\u062c\u0648\u0645 \u0642\u0631\u0627\u0631 \u0628\u062f\u0647\u062f. \u063a\u0644\u0627\u062a\u060c \u0633\u0628\u0632\u06cc\u200c\u0647\u0627\u060c \u0635\u06cc\u0641\u06cc\u200c\u062c\u0627\u062a \u0648 \u062d\u062a\u06cc \u0628\u0639\u0636\u06cc \u0627\u0632 \u0645\u06cc\u0648\u0647\u200c\u0647\u0627 \u0646\u06cc\u0632 \u0627\u0632 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u062f\u0631 \u0627\u0645\u0627\u0646 \u0646\u06cc\u0633\u062a\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0627\u0632 <a href=\"https:\/\/pesterafsanjan.com\/blog\/\">\u0645\u062c\u0644\u0647 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u067e\u0633\u062a\u0647 \u0631\u0641\u0633\u0646\u062c\u0627\u0646<\/a>\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0622\u0641\u062a \u0633\u0648\u0633\u06a9 \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645. \u0628\u0627 \u0645\u0627 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0628\u0627 \u0645\u06cc\u0632\u0627\u0646 \u062e\u0633\u0627\u0631\u062a \u0627\u06cc\u0646 \u0622\u0641\u062a \u0648 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0622\u0646 \u0622\u0634\u0646\u0627 \u0634\u0648\u06cc\u062f.<\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u0647\u0645 \u0622\u0641\u062a \u0633\u0631 \u062e\u0631\u0637\u0648\u0645\u06cc<\/strong><\/h2>\n\n\n\n<p>\u062f\u0631 \u0645\u0646\u0627\u0637\u0642 \u0633\u0631\u062f\u0633\u06cc\u0631 \u062f\u0631 \u0632\u0645\u0633\u062a\u0627\u0646 \u0628\u0647 \u0634\u06a9\u0644 \u062d\u0634\u0631\u0647 \u06a9\u0627\u0645\u0644 \u062f\u0631 \u0628\u0642\u0627\u06cc\u0627\u06cc \u0645\u062d\u0635\u0648\u0644 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u0648 \u062f\u0631 \u0645\u0646\u0627\u0637\u0642 \u0645\u0639\u062a\u062f\u0644\u200c\u062a\u0631 \u0628\u0647 \u0634\u06a9\u0644 \u0631\u062f\u06cc\u0641\u200c\u0647\u0627\u06cc \u062a\u062e\u0645 \u06f3 \u062a\u0627 \u06f6\u06f0 \u062a\u0627\u06cc\u06cc \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u0646\u062f.<\/p>\n\n\n\n<p>\u0628\u0627 \u06af\u0631\u0645 \u0634\u062f\u0646 \u0647\u0648\u0627 \u0648 \u0631\u0633\u06cc\u062f\u0646 \u062f\u0645\u0627 \u0628\u0647 \u06f1\u06f7 \u062f\u0631\u062c\u0647 \u0633\u0627\u0646\u062a\u06cc\u200c\u06af\u0631\u0627\u062f\u060c \u062d\u0634\u0631\u0627\u062a \u0634\u0631\u0648\u0639 \u0628\u0647 \u062a\u062e\u0645\u200c\u06af\u0630\u0627\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u062c\u0646\u06cc\u0646\u06cc \u0628\u06cc\u0646 \u06f5 \u062a\u0627 \u06f1\u06f5 \u0631\u0648\u0632 \u0627\u0633\u062a.<\/p>\n\n\n\n<p>\ufefb\u0631\u0648\ufeeb\ufe8e\u06cc \ufeb3\ufee6 \u0627\u0648\u0644 \u0627\ufe91\ufe98\ufeaa\u0627 \u0627\u0632 \u062c\u0648\u0627\u0646\u0647\u200c\u0647\u0627 \u0648 \u0628\u0631\u06af\u200c\u0647\u0627\u06cc \ufedf\ufec4\ufbff\ufed2 <a href=\"https:\/\/pesterafsanjan.com\/blog\/tag\/%db%8c%d9%88%d9%86%d8%ac%d9%87\">\ufbfe\ufeee\ufee7\ufea0\ufeea<\/a> \ufe97\ufed0\ufeac\ufbfe\ufeea \ufb90\ufeae\u062f\u0647 \u0648 \u062f\u0631 \ufeb3\ufee8\ufbff\ufee6 \ufe91\ufecc\ufeaa\u06cc \u0627\u0632 \ufeb3\ufe8e\ufbfe\ufeae \ufe91\ufeae\u06af\u200c\u0647\u0627 \ufe97\ufed0\ufeac\ufbfe\ufeea \u06a9\u0631\u062f\u0647 \u0648 \ufe91\ufeae\u06af\u200c\u0647\u0627 \u0631\u0627 \ufeb3\ufeee\u0631\u0627\u062e \u0648 \ufee3\ufeb8\ufe92\ufb8f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n\n\n\n<p>\u062f\u0631 \u062d\u0645\u0644\u0647\u200c\u0647\u0627\u06cc \ufeb7\ufeaa\ufbfe\ufeaa\u060c \u0628\u0631\u06af\u200c\u0647\u0627 \ufea7\ufeb8\ufb91\ufbff\ufeaa\u0647 \u0648 \ufb94\ufe8e\ufeeb\ufbfd \ufe91\ufeea \ufecb\ufee0\ufe96 \ufed3\ufed8\ufeaa\u0627\u0646 \ufb90\ufee0\ufeae\u0648\ufed3\ufbff\ufede \ufee3\ufeb0\u0631\ufecb\ufeea \u0627\u0632 \u062f\u0648\u0631 \u0633\u0641\u06cc\u062f\u0631\u0646\u06af \ufe91\ufeea \ufee7\ufec8\ufeae \u0645\u06cc\u200c\u0631\u0633\u062f. \ufed3\ufecc\ufe8e\ufedf\ufbff\ufe96 \ufefb\u0631\u0648\ufeeb\ufe8e \ufe91\ufbff\ufeb8\ufe98\ufeae \u062f\u0631 \ufeb3\ufe8e\ufecb\ufe8e\u062a \ufea7\ufee8\ufb8f \u0631\u0648\u0632 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/pesterafsanjan.com\/blog\/%D9%82%DB%8C%D9%85%D8%AA-%D9%BE%D8%B3%D8%AA%D9%87-%D8%A7%D9%85%D8%B1%D9%88%D8%B2\"><img decoding=\"async\" width=\"900\" height=\"150\" src=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2020\/03\/show-in-blog-5-1.gif\" alt=\"\u0642\u06cc\u0645\u062a \u067e\u0633\u062a\u0647\" class=\"wp-image-75188\"\/><\/a><\/figure><\/div>\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0645\u0631\u062d\u0644\u0647 \u062c\u0646\u06cc\u0646\u06cc \u0648 \u062a\u062e\u0645 \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647<\/strong><\/h2>\n\n\n\n<p>\u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0645\u0627\u0646\u0646\u062f \u062f\u06cc\u06af\u0631 \u062d\u0634\u0631\u0627\u062a \u0627\u06af\u0631 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0645\u0646\u0627\u0633\u0628 \u0628\u0627\u0634\u062f \u0634\u0631\u0648\u0639 \u0628\u0647 \u0632\u0627\u062f\u0648\u0648\u0644\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0628\u0647\u200c\u0633\u0631\u0639\u062a \u0632\u06cc\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u0645\u0648\u0631\u062f \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u062d\u062a\u06cc \u062c\u0645\u0639\u06cc\u062a \u06a9\u0645 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0627\u062a \u0646\u06cc\u0632 \u0646\u06af\u0631\u0627\u0646\u06cc\u200c\u0627\u06cc \u0628\u0632\u0631\u06af \u0628\u0631\u0627\u06cc \u0622\u06cc\u0646\u062f\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0627\u0634\u062f.<\/p>\n\n\n\n<p>\u0645\u0631\u0627\u062d\u0644 \u0631\u0634\u062f \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0646\u06cc\u0632 \u0645\u0627\u0646\u0646\u062f \u062f\u06cc\u06af\u0631 \u062d\u0634\u0631\u0627\u062a \u0627\u0632 \u062a\u062e\u0645 \u0622\u063a\u0627\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0633\u067e\u0633 \u0628\u0647\u200c\u0635\u0648\u0631\u062a \u0644\u0627\u0631\u0648 \u0633\u0631 \u0627\u0632 \u062a\u062e\u0645 \u0628\u06cc\u0631\u0648\u0646 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f \u0648 \u0642\u0628\u0644 \u0627\u0632 \u062a\u0628\u062f\u06cc\u0644\u200c\u0634\u062f\u0646 \u0628\u0647 \u062d\u0634\u0631\u0647 \u06a9\u0627\u0645\u0644 \u0628\u0631\u0627\u06cc \u0645\u062f\u062a\u06cc \u0634\u0641\u06cc\u0631\u0647 \u0645\u06cc\u200c\u0645\u0627\u0646\u062f.<\/p>\n\n\n\n<p>\u062f\u0631 \u062a\u0645\u0627\u0645\u06cc \u0645\u0631\u0627\u062d\u0644 \u0631\u0634\u062f \u0628\u0647 \u063a\u06cc\u0631 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u062a\u062e\u0645 \u0627\u0633\u062a\u060c \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0647 \u0645\u062d\u0635\u0648\u0644 \u0646\u0647\u0627\u06cc\u06cc \u0636\u0631\u0628\u0647 \u0645\u06cc\u200c\u0632\u0646\u062f.<\/p>\n\n\n\n<p>\u0627\u0648\u0644\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0631\u0634\u062f \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u06cc\u0639\u0646\u06cc \u062c\u0646\u06cc\u0646 \u062f\u0631 \u062d\u062f\u0648\u062f \u06f5 \u0627\u0644\u06cc \u06f1\u06f5 \u0631\u0648\u0632 \u0637\u0648\u0644 \u0645\u06cc\u200c\u06a9\u0634\u062f. \u0648\u0627\u0628\u0633\u062a\u0647 \u0628\u0647 \u0646\u0648\u0639 \u062d\u0634\u0631\u0647 \u0648 \u06af\u06cc\u0627\u0647 \u0645\u06cc\u0632\u0628\u0627\u0646 \u0627\u06cc\u0646 \u0645\u062f\u062a\u200c\u0632\u0645\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u062a\u0641\u0627\u0648\u062a \u0628\u0627\u0634\u062f.<\/p>\n\n\n\n<p>\u062a\u062e\u0645\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0647 \u0631\u0646\u06af \u0632\u0631\u062f \u0644\u06cc\u0645\u0648\u06cc\u06cc \u0634\u0641\u0627\u0641 \u0647\u0633\u062a\u0646\u062f\u061b \u06a9\u0647 \u0639\u0631\u0636 \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u062d\u062f\u0648\u062f \u06f0.\u06f3 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0648 \u0637\u0648\u0644 \u0622\u0646\u200c\u0647\u0627 \u0628\u06cc\u0646 \u06f5.\u06f5 \u2013 \u06f0.\u06f4 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062a\u062e\u0645\u200c\u0647\u0627 \u062f\u0631 \u0627\u0648\u0627\u062e\u0631 \u062f\u0648\u0631\u0647 \u062c\u0646\u06cc\u0646\u06cc \u062d\u0634\u0631\u0647 \u0628\u0647 \u0631\u0646\u06af \u062a\u06cc\u0631\u0647 \u062f\u0631\u0645\u06cc\u200c\u0622\u06cc\u0646\u062f.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u0645\u0631\u0627\u062d\u0644 \u0632\u0646\u062f\u06af\u06cc \u0644\u0627\u0631\u0648\u06cc \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc<\/h2>\n\n\n\n<p>\u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0639\u062f \u0627\u0632 \u0645\u0631\u062d\u0644\u0647 \u062c\u0646\u06cc\u0646\u06cc \u0648 \u0628\u0639\u062f \u0627\u0632 \u062e\u0627\u0631\u062c \u0634\u062f\u0646 \u0627\u0632 \u062a\u062e\u0645\u200c\u0647\u0627 \u062a\u0628\u062f\u06cc\u0644 \u0628\u0647 \u0644\u0627\u0631\u0648 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0642\u0628\u0644 \u0627\u0632 \u062a\u0628\u062f\u06cc\u0644\u200c\u0634\u062f\u0646 \u0628\u0647 \u0634\u0641\u06cc\u0631\u0647 \u0644\u0627\u0631\u0648 \u0622\u0641\u062a \u0633\u0648\u0633\u06a9 \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647\u060c \u06f4 \u0645\u0631\u062d\u0644\u0647 \u0631\u0627 \u0633\u067e\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a \u0627\u0633\u062a:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u06f1<\/strong><strong>.<\/strong><strong> \u0645\u0631\u062d\u0644\u0647 \u0627\u0648\u0644 \u0644\u0627\u0631\u0648\u06cc \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc<\/strong><\/h3>\n\n\n\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0644\u0627\u0631\u0648 \u062d\u0634\u0631\u0647 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0648\u0686\u06a9 \u0627\u0633\u062a \u0648 \u0627\u0646\u062f\u0627\u0632\u0647\u200c\u0627\u06cc \u0628\u06cc\u0646 1 \u2013 1.2 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u062f\u0627\u0631\u062f. \u0631\u0646\u06af \u0628\u062f\u0646 \u0622\u0646 \u0633\u0641\u06cc\u062f \u0634\u06cc\u0631\u06cc\u200c\u0631\u0646\u06af \u0645\u0627\u06cc\u0644 \u0628\u0647 \u0632\u0631\u062f \u0627\u0633\u062a.<\/p>\n\n\n\n<p>\u062f\u0631 \u0642\u0633\u0645\u062a \u0633\u0631 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u06a9\u067e\u0633\u0648\u0644\u06cc \u0642\u0647\u0648\u0647\u200c\u0627\u06cc\u200c\u0631\u0646\u06af \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0622\u0646 \u0639\u0644\u0627\u0645\u062a\u06cc \u0628\u0647 \u0634\u06a9\u0644 Y \u0628\u0647 \u0631\u0646\u06af \u0633\u0641\u06cc\u062f \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u0648 \u0642\u0627\u0628\u0644\u200c\u062a\u0634\u062e\u06cc\u0635 \u0627\u0633\u062a. \u0642\u0637\u0631 \u0627\u06cc\u0646 \u06a9\u067e\u0633\u0648\u0644 0.15 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0627\u0633\u062a.<\/p>\n\n\n\n<p>\u0631\u0648\u06cc \u067e\u06cc\u0634 \u06af\u0631\u062f\u0647\u060c \u0644\u06a9\u0647 \u0645\u062b\u0644\u062b\u06cc \u0634\u06a9\u0644\u06cc \u0646\u06cc\u0632 \u0645\u0648\u062c\u0648\u062f \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u062e\u0637\u06cc \u0633\u0641\u06cc\u062f \u0628\u0647 \u062f\u0648 \u0646\u06cc\u0645 \u062a\u0642\u0633\u06cc\u0645\u200c\u0634\u062f\u0647 \u0627\u0633\u062a. \u0628\u062f\u0646 \u0627\u06cc\u0646 \u0644\u0627\u0631\u0648 \u067e\u0648\u0634\u06cc\u062f\u0647 \u0628\u0627 \u0645\u0648\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0647\u0631 \u062d\u0644\u0642\u0647 \u06f8 \u0639\u062f\u062f \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.<\/p>\n\n\n\n<p>\u0642\u0627\u0626\u062f\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0647\u0627 \u0628\u0647 \u0631\u0646\u06af \u0642\u0647\u0648\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u0648 \u06f4 \u0639\u062f\u062f \u062f\u0631 \u0627\u0637\u0631\u0627\u0641 \u0648 \u06f4 \u0645\u0648 \u062f\u0631 \u0633\u0637\u062d \u067e\u0634\u062a\u06cc \u062d\u0634\u0631\u0647 \u062f\u0631 \u0647\u0631 \u062d\u0644\u0642\u0647 \u062f\u06cc\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u062d\u0634\u0631\u0647 \u062f\u0631 \u062c\u0648\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632\u06cc \u062a\u063a\u0630\u06cc\u0647 \u0648 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u06f2<\/strong><strong>.<\/strong><strong> \u062f\u0648\u0631\u0647 \u062f\u0648\u0645 \u0644\u0627\u0631\u0648\u06cc \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc<\/strong><\/h3>\n\n\n\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u062f\u0648\u0631\u0647 \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc \u0644\u0627\u0631\u0648\u060c \u0628\u0647 \u0639\u0644\u062a \u062a\u063a\u0630\u06cc\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0637\u0648\u0644 \u0622\u0646 \u0628\u0647 \u06f3 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f. \u0631\u0646\u06af \u0628\u062f\u0646 \u0627\u06cc\u0646 \u0644\u0627\u0631\u0648 \u0627\u0632 \u0632\u0631\u062f \u0628\u0647 \u0633\u0628\u0632 \u062a\u0645\u0627\u06cc\u0644 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f \u0627\u0645\u0627 \u0628\u0642\u06cc\u0647 \u0645\u0634\u062e\u0635\u0627\u062a \u0644\u0627\u0631\u0648 \u0645\u0627\u0646\u0646\u062f \u062f\u0648\u0631\u0647 \u0642\u0628\u0644\u06cc \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0627\u0633\u062a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u06f3<\/strong><strong>.<\/strong><strong> \u062f\u0648\u0631\u0647 \u0633\u0648\u0645 \u0644\u0627\u0631\u0648\u06cc \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc<\/strong><\/h3>\n\n\n\n<p>\u0637\u0648\u0644 \u0644\u0627\u0631\u0648 \u0622\u0641\u062a \u0633\u0648\u0633\u06a9 \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0628\u0647 \u06f6 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f \u0648 \u0631\u0646\u06af \u0628\u062f\u0646 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u06a9\u0627\u0645\u0644\u0627\u064b \u0633\u0628\u0632 \u0631\u0648\u0634\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n\n\n\n<p>\u0628\u0627\u0627\u06cc\u0646\u06a9\u0647 \u06f3 \u062f\u0648\u0631\u0647 \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc \u0644\u0627\u0631\u0648\u06cc \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0645\u06cc\u200c\u06af\u0630\u0631\u062f \u0627\u0645\u0627 \u0647\u0645\u0686\u0646\u0627\u0646 \u062f\u0631 \u062c\u0648\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632\u06cc \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0627\u0632 \u0647\u0645\u0627\u0646 \u062c\u0648\u0627\u0646\u0647\u200c\u0647\u0627 \u062a\u063a\u0630\u06cc\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u067e\u0631\u0632\u0647\u0627\u06cc \u0628\u062f\u0646 \u0644\u0627\u0631\u0648 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u06f4<\/strong><strong>.<\/strong><strong> \u062f\u0648\u0631\u0647 \u0686\u0647\u0627\u0631\u0645 \u0644\u0627\u0631\u0648\u06cc \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc<\/strong><\/h3>\n\n\n\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u062f\u0648\u0631\u0647 \u0637\u0648\u0644 \u0628\u062f\u0646 \u0627\u06cc\u0646 \u0644\u0627\u0631\u0648 \u0628\u0647 \u06f1\u06f2 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f. \u0631\u0646\u06af \u0628\u062f\u0646 \u0622\u0646 \u0628\u0647 \u0633\u0628\u0632 \u062a\u06cc\u0631\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0646\u0648\u0627\u0631 \u0633\u0641\u06cc\u062f\u0631\u0646\u06af\u06cc \u062f\u0631 \u0642\u0633\u0645\u062a \u0645\u06cc\u0627\u0646\u06cc \u0628\u062f\u0646 \u0622\u0646 \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n\n\n\n<p>\u062f\u0631 \u0642\u0633\u0645\u062a \u0634\u06a9\u0645\u06cc \u0647\u0631 \u062d\u0644\u0642\u0647 \u0627\u0632 \u0628\u062f\u0646 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u06cc\u06a9 \u062c\u0641\u062a \u0628\u0631\u0622\u0645\u062f\u06af\u06cc \u0646\u0633\u0628\u062a\u0627\u064b \u0628\u0632\u0631\u06af \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0627\u0628\u0632\u0627\u0631 \u062d\u0631\u06a9\u062a\u06cc \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631 \u0647\u0631 \u062d\u0644\u0642\u0647 \u062a\u0639\u062f\u0627\u062f \u0645\u0633\u0627\u0648\u06cc \u0631\u0648\u0632\u0646\u0647\u200c\u0647\u0627\u06cc \u062a\u0646\u0641\u0633\u06cc \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n\n\n\n<p>\u062f\u0631 \u0627\u0646\u062a\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0644\u0627\u0631\u0648 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u062a\u0628\u062f\u06cc\u0644 \u0628\u0647 \u0634\u0641\u06cc\u0631\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2016\/08\/1-4.jpg\" alt=\"\u0633\u0648\u0633\u06a9 \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647\" class=\"wp-image-78615\" srcset=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2016\/08\/1-4.jpg 768w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2016\/08\/1-4-300x169.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0645\u0631\u062d\u0644\u0647 \u0632\u0646\u062f\u06af\u06cc \u0634\u0641\u06cc\u0631\u0647\u200c\u0627\u06cc \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc<\/strong><\/h2>\n\n\n\n<p>\u0644\u0627\u0631\u0648 \u0622\u0641\u062a \u0633\u0648\u0633\u06a9 \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647 \u0628\u0639\u062f \u0627\u0632 \u06af\u0630\u0631\u0627\u0646\u062f\u0646 \u0622\u062e\u0631\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0644\u0627\u0631\u0648 \u0628\u0631\u0627\u06cc \u062a\u0628\u062f\u06cc\u0644\u200c\u0634\u062f\u0646 \u0628\u0647 \u0634\u0641\u06cc\u0631\u0647 \u0628\u0647 \u062f\u0648\u0631 \u062e\u0648\u062f \u067e\u06cc\u0644\u0647 \u0645\u06cc\u200c\u0628\u0646\u062f\u062f.<\/p>\n\n\n\n<p>\u0627\u06cc\u0646 \u067e\u06cc\u0644\u0647\u200c\u06cc \u0645\u0634\u0628\u06a9 \u0648 \u0633\u0641\u06cc\u062f\u0631\u0646\u06af \u0628\u0639\u062f \u0627\u0632 \u06af\u0630\u0634\u062a \u0632\u0645\u0627\u0646 \u062a\u063a\u06cc\u06cc\u0631 \u062d\u0634\u0631\u0647 \u0634\u06a9\u0627\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0634\u0641\u06cc\u0631\u0647 \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647 \u0628\u06cc\u0631\u0648\u0646 \u0645\u06cc\u200c\u0622\u06cc\u062f. \u0627\u06cc\u0646 \u0634\u0641\u06cc\u0631\u0647 \u0627\u0632 \u0646\u0648\u0639 \u0622\u0632\u0627\u062f \u0627\u0633\u062a\u061b<\/p>\n\n\n\n<p>\u06cc\u0639\u0646\u06cc \u0634\u0627\u062e\u06a9\u200c\u0647\u0627\u060c \u067e\u0627\u0647\u0627 \u0648 \u06a9\u0644\u0627\u064b \u0647\u0631\u06a9\u062f\u0627\u0645 \u0627\u0632 \u0627\u0646\u062f\u0627\u0645\u200c\u0647\u0627\u06cc \u0628\u062f\u0646 \u0628\u0647 \u0628\u062f\u0646 \u0646\u0686\u0633\u0628\u06cc\u062f\u0647 \u0648 \u06cc\u0627 \u062a\u0648\u0633\u0637 \u0647\u06cc\u0686 \u0645\u062e\u0627\u0637\u060c \u06cc\u0627 \u063a\u0634\u0627\u06cc\u06cc \u0645\u062d\u062f\u0648\u062f \u0648 \u0645\u0647\u0627\u0631 \u0646\u0634\u062f\u0647\u200c\u0627\u0646\u062f.<\/p>\n\n\n\n<p>\u0637\u0648\u0644 \u0627\u06cc\u0646 \u0634\u0641\u06cc\u0631\u0647 \u062f\u0631 \u062d\u062f\u0648\u062f \u06f8 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0648 \u0639\u0631\u0636 \u0622\u0646 \u0628\u06cc\u0646 \u06f5 \u2013 \u06f7 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0645\u062a\u063a\u06cc\u0631 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u062f\u0646\u06cc \u0628\u0647 \u0634\u06a9\u0644 \u0645\u062b\u0644\u062b \u062f\u0627\u0631\u062f. \u0631\u0646\u06af \u0622\u0646 \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0632\u0631\u062f \u0645\u062a\u0645\u0627\u06cc\u0644 \u0628\u0647 \u0633\u0628\u0632 \u0627\u0633\u062a \u0627\u0645\u0627 \u0628\u0639\u062f \u0627\u0632 \u0645\u062f\u062a\u06cc \u0628\u0647 \u0631\u0646\u06af \u0633\u0628\u0632 \u062a\u06cc\u0631\u0647 \u0645\u062a\u0645\u0627\u06cc\u0644 \u0628\u0647 \u0642\u0647\u0648\u0647\u200c\u0627\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0636\u0645\u0627\u0626\u0645 \u062e\u0627\u0631\u062c\u06cc \u0622\u0646 \u0627\u0632 \u0628\u0642\u06cc\u0647 \u0642\u0633\u0645\u062a\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u062a\u06cc\u0631\u0647\u200c\u062a\u0631 \u0627\u0633\u062a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u062d\u0634\u0631\u0647 \u06a9\u0627\u0645\u0644 \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc<\/strong><\/h2>\n\n\n\n<p>\u062f\u0631 \u062f\u0648 \u0637\u0631\u0641 \u062e\u0631\u0637\u0648\u0645 \u0622\u0646\u200c\u0647\u0627 \u0634\u06cc\u0627\u0631\u06cc \u0628\u0647 \u0637\u0648\u0644 \u062a\u0642\u0631\u06cc\u0628\u06cc 1.2 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0646\u062f \u0627\u0648\u0644 \u0634\u0627\u062e\u06a9 \u062f\u0631 \u0622\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0634\u0627\u062e\u06a9 \u0627\u0632 \u062a\u06cc\u067e \u0632\u0627\u0646\u0648\u06cc\u06cc \u0628\u0648\u062f\u0647 \u0648 \u0645\u062a\u0634\u06a9\u0644 \u0627\u0632 \u06f1\u06f2 \u0628\u0646\u062f \u0645\u06cc\u200c\u0628\u0627\u0634\u062f.<\/p>\n\n\n\n<p>\u0628\u0631 \u0631\u0648\u06cc \u0634\u0627\u062e\u06a9 \u0646\u06cc\u0632 \u062a\u0639\u062f\u0627\u062f\u06cc \u0632\u06cc\u0627\u062f\u06cc \u06a9\u0631\u06a9\u060c \u0628\u0647 \u0631\u0646\u06af \u0633\u0641\u06cc\u062f \u0645\u0627\u06cc\u0644 \u0628\u0647 \u0632\u0631\u062f \u062f\u06cc\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0646\u062f\u0647\u0627\u06cc \u0642\u0627\u0639\u062f\u0647\u200c\u0627\u06cc \u0628\u0627\u0631\u06cc\u06a9 \u0628\u0648\u062f\u0647 \u0648\u0644\u06cc \u0628\u0646\u062f\u0647\u0627\u06cc \u0627\u0646\u062a\u0647\u0627\u06cc\u06cc \u06cc\u06a9\u200c\u0645\u0631\u062a\u0628\u0647 \u0642\u0637\u0648\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u0627\u06cc\u0646 \u062a\u063a\u06cc\u06cc\u0631 \u0634\u06a9\u0644 \u062a\u0627 \u0628\u0646\u062f \u0622\u062e\u0631 \u0628\u0647\u200c\u062e\u0648\u0628\u06cc \u0645\u062d\u0633\u0648\u0633 \u0627\u0633\u062a.<\/p>\n\n\n\n<p>\u0686\u0634\u0645\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0628 \u0628\u0647 \u0631\u0646\u06af \u0633\u06cc\u0627\u0647 \u0628\u0627 \u062c\u0644\u0627\u06cc \u0641\u0644\u0632\u06cc \u0648 \u0628\u06cc\u0636\u06cc\u200c\u0634\u06a9\u0644 \u0645\u06cc\u200c\u0628\u0627\u0634\u0646\u062f. \u0633\u0631\u060c \u0628\u0647\u200c\u0627\u0633\u062a\u062b\u0646\u0627\u06cc \u0686\u0634\u0645\u200c\u0647\u0627 \u0627\u0632 \u0645\u0648\u0647\u0627\u06cc\u06cc \u0628\u0647 \u0631\u0646\u06af \u0632\u0631\u062f \u0631\u0648\u0634\u0646 \u067e\u0648\u0634\u06cc\u062f\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a. \u067e\u06cc\u0634 \u0642\u0641\u0633\u0647 \u0633\u06cc\u0646\u0647 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u0628\u06cc\u0636\u06cc\u200c\u0634\u06a9\u0644 \u0628\u0648\u062f\u0647 \u0648 \u062f\u0631 \u0648\u0633\u0637 \u0642\u0637\u0648\u0631\u062a\u0631 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f.<\/p>\n\n\n\n<p>\u062f\u0631 \u067e\u06cc\u0634 \u06af\u0631\u062f\u0647 \u062f\u0648 \u0646\u0648\u0627\u0631 \u0633\u06cc\u0627\u0647\u200c\u0631\u0646\u06af \u0628\u0627 \u0639\u0631\u0636 \u062a\u0642\u0631\u06cc\u0628\u06cc \u06cc\u06a9 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0647\u200c\u0648\u0633\u06cc\u0644\u0647 \u0646\u0648\u0627\u0631 \u0633\u0641\u06cc\u062f\u0631\u0646\u06af \u0628\u0627\u0631\u06cc\u06a9\u06cc \u0627\u0632 \u0647\u0645 \u062c\u062f\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0627\u06cc\u0646 \u0646\u0648\u0627\u0631 \u062f\u0631\u0633\u062a \u062f\u0631 \u0627\u0645\u062a\u062f\u0627\u062f \u062e\u0631\u0637\u0648\u0645 \u062d\u0634\u0631\u0647 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u062f. \u0637\u0648\u0644 \u0628\u0627\u0644 \u067e\u0648\u0634\u200c\u0647\u0627 3.5 \u0628\u0631\u0627\u0628\u0631 \u0639\u0631\u0636 \u0622\u0646\u200c\u0647\u0627 \u0628\u0648\u062f\u0647\u060c \u0628\u0627\u0644 \u067e\u0648\u0634\u200c\u0647\u0627 \u062f\u0631 \u0627\u0646\u062a\u0647\u0627\u06cc \u0628\u062f\u0646 \u0642\u0648\u0633\u06cc \u0634\u06a9\u0644 \u0647\u0633\u062a\u0646\u062f.<\/p>\n\n\n\n<p>\u062f\u0631 \u0631\u0648\u06cc \u0628\u0627\u0644 \u067e\u0648\u0634\u200c\u0647\u0627 \u0648 \u062f\u0631 \u0627\u0645\u062a\u062f\u0627\u062f \u0646\u0648\u0627\u0631 \u067e\u06cc\u0634 \u06af\u0631\u062f\u0647\u060c \u0646\u0648\u0627\u0631\u06cc \u0628\u0647 \u0647\u0645\u0627\u0646 \u0631\u0646\u06af \u06a9\u0634\u06cc\u062f\u0647 \u0634\u062f\u0647 \u06a9\u0647 \u062a\u0627 \u062f\u0648\u0633\u0648\u0645 \u0637\u0648\u0644 \u0628\u0627\u0644 \u067e\u0648\u0634\u200c\u0647\u0627 \u0627\u0645\u062a\u062f\u0627\u062f \u062f\u0627\u0631\u062f \u0648 \u0627\u0646\u062a\u0647\u0627\u06cc \u0646\u0648\u0627\u0631\u0647\u0627 \u0628\u0627\u0631\u06cc\u06a9\u200c\u062a\u0631 \u0627\u0632 \u0627\u0628\u062a\u062f\u0627\u06cc \u0622\u0646\u200c\u0647\u0627\u0633\u062a.<\/p>\n\n\n\n<p>\u062f\u0631 \u0631\u0648\u06cc \u0647\u0631 \u0628\u0627\u0644 \u067e\u0648\u0634\u060c \u0641\u0631\u0648\u0631\u0641\u062a\u06af\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0634\u06cc\u0627\u0631\u0647\u0627\u06cc\u06cc \u0631\u0627 \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u06cc\u0646 \u0634\u06cc\u0627\u0631\u0647\u0627 \u0645\u062c\u0647\u0632 \u0628\u0647 \u062e\u0627\u0631\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062a\u0634\u06a9\u06cc\u0644 \u0631\u062f\u06cc\u0641\u200c\u0647\u0627\u06cc \u0645\u0646\u0638\u0645\u06cc \u0631\u0627 \u062f\u0627\u062f\u0647 \u0648 \u0641\u0627\u0635\u0644\u0647 \u0622\u0646\u200c\u0647\u0627 \u0627\u0632 \u06cc\u06a9\u062f\u06cc\u06af\u0631 0.2 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631 \u0627\u0633\u062a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u06af\u06cc\u0627\u0647\u0627\u0646 \u0645\u0648\u0631\u062f \u0647\u062f\u0641 \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc<\/strong><\/h2>\n\n\n\n<p>\u0627\u06cc\u0646 \u0622\u0641\u062a \u06af\u06cc\u0627\u0647\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0645\u0648\u0631\u062f\u062d\u0645\u0644\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u062f \u0648 \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646\u200c\u0647\u0627 \u0628\u0647 \u062e\u0648\u062f \u06af\u06cc\u0627\u0647 \u0648 \u0645\u062d\u0635\u0648\u0644 \u0646\u0647\u0627\u06cc\u06cc \u0622\u0633\u06cc\u0628 \u0648\u0627\u0631\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f. \u06af\u06cc\u0627\u0647\u0627\u0646\u06cc \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0622\u0633\u06cc\u0628 \u0631\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u0622\u0641\u062a \u0645\u06cc\u200c\u0628\u06cc\u0646\u0646\u062f \u06cc\u0648\u0646\u062c\u0647 \u0648 \u062e\u0631\u0645\u0627 \u0628\u0648\u062f\u0646\u062f.<\/p>\n\n\n\n<p>\u0628\u0647\u200c\u062a\u0627\u0632\u06af\u06cc \u0646\u0648\u0639\u06cc \u062c\u062f\u06cc\u062f \u0627\u0632 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0634\u0646\u0627\u062e\u062a\u0647\u200c\u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 <a href=\"https:\/\/pesterafsanjan.com\/blog\/tag\/%D9%BE%D8%B3%D8%AA%D9%87\">\u067e\u0633\u062a\u0647<\/a> \u062d\u0645\u0644\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0634\u0627\u0648\u0631\u0632\u0627\u0646 \u0631\u0627 \u0646\u06af\u0631\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0627\u0646\u0648\u0627\u0639 \u0627\u06cc\u0646 \u0622\u0641\u062a \u0631\u0627 \u0628\u0627 \u0627\u0633\u0645 \u06af\u06cc\u0627\u0647 \u0645\u06cc\u0632\u0628\u0627\u0646 \u0622\u0646 \u0645\u06cc\u200c\u0634\u0646\u0627\u0633\u0646\u062f.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2016\/08\/2-2.jpg\" alt=\"\u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647\" class=\"wp-image-78616\" srcset=\"https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2016\/08\/2-2.jpg 768w, https:\/\/pesterafsanjan.com\/blog\/wp-content\/uploads\/2016\/08\/2-2-300x169.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0622\u0641\u062a \u0633\u0648\u0633\u06a9 \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647<\/strong><\/h3>\n\n\n\n<p>\u0627\u06cc\u0646 \u0622\u0641\u062a \u0645\u0627\u0646\u0646\u062f \u062f\u06cc\u06af\u0631 \u0647\u0645\u200c\u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u062e\u0648\u062f \u0627\u0632 \u062a\u062e\u0645 \u062e\u0627\u0631\u062c \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0628\u0639\u062f \u0627\u0632 \u06af\u0630\u0631\u0627\u0646\u062f\u0646 \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0644\u0627\u0631\u0648\u06cc \u0648 \u0634\u0641\u06cc\u0631\u0647\u200c\u0627\u06cc \u0628\u0647 \u062d\u0634\u0631\u0647 \u0628\u0627\u0644\u063a \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n\n\n\n<p>\u0645\u062d\u0644 \u062a\u063a\u0630\u06cc\u0647 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0627\u0641\u062a\u0647\u200c\u0627\u06cc \u0646\u0631\u0645 \u06af\u06cc\u0627\u0647\u060c \u0628\u0627\u0641\u062a\u0647\u200c\u0627\u06cc \u0633\u0628\u0632 \u062c\u0648\u0627\u0646\u060c \u0628\u0627\u0641\u062a\u0647\u200c\u0627\u06cc \u0631\u0648\u06cc\u0634\u06cc \u0648 \u0632\u0627\u06cc\u0634\u06cc \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u0637\u0628\u06cc\u0639\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627 \u0631\u0634\u062f \u0627\u06cc\u0646 \u0628\u0627\u0641\u062a \u0647\u0627 \u0632\u06cc\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u0648\u0627\u062e\u0631 \u0627\u0633\u0641\u0646\u062f\u0645\u0627\u0647 \u0648 \u0627\u0648\u0627\u06cc\u0644 \u0641\u0635\u0644 \u0628\u0647\u0627\u0631 \u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u0638\u0647\u0648\u0631 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0645\u06cc\u200c\u0628\u0627\u0634\u0646\u062f.<\/p>\n\n\n\n<p>\u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0631\u062e\u0644\u0627\u0641 \u0647\u0645\u200c\u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062e\u0648\u062f\u060c \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u06cc\u0648\u0646\u062c\u0647 \u062f\u0631 \u062c\u0648\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632\u06cc \u0631\u0634\u062f \u0646\u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0644\u06a9\u0647 \u062f\u0631 \u0644\u0627\u0628\u0647\u200c\u0644\u0627\u06cc \u0628\u0642\u0627\u06cc\u0627\u06cc \u067e\u0648\u0633\u06cc\u062f\u0647 \u0628\u0627\u0642\u06cc\u200c\u0645\u0627\u0646\u062f\u0647 \u062f\u0631 \u0632\u06cc\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u062a\u062e\u0645 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u0646\u062f \u0648 \u06f3 \u062f\u0648\u0631\u0647 \u0632\u0646\u062f\u06af\u06cc \u0642\u0628\u0644 \u0627\u0632 \u062f\u0648\u0631\u0627\u0646 \u0628\u0644\u0648\u063a \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0622\u0646\u062c\u0627 \u0645\u06cc\u200c\u06af\u0630\u0631\u0627\u0646\u0646\u062f.<\/p>\n\n\n\n<p>\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647 \u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u062a\u0645\u06cc\u0632 \u0646\u06af\u0647\u200c\u062f\u0627\u0634\u062a\u0646 \u0632\u06cc\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u0627\u0633\u062a. \u067e\u0627 \u0628\u06cc\u0644 \u0648 \u0634\u062e\u0645 \u0632\u062f\u0646 \u0632\u0645\u06cc\u0646 \u0647\u0645 \u062f\u0631 \u06a9\u0646\u062a\u0631\u0644 \u0627\u06cc\u0646 \u0622\u0641\u062a \u062f\u0631 \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u067e\u0633\u062a\u0647 \u0628\u06cc\u200c\u062a\u0623\u062b\u06cc\u0631 \u0646\u06cc\u0633\u062a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u0634\u0646\u0627\u062e\u062a \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u062e\u0631\u0645\u0627<\/strong><\/h3>\n\n\n\n<p>\u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0646\u06cc\u0632 \u0645\u0627\u0646\u0646\u062f \u0647\u0645\u200c\u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0622\u0646 \u0627\u0632 \u0686\u0647\u0627\u0631 \u0645\u0631\u062d\u0644\u0647 \u0632\u0646\u062f\u06af\u06cc \u062a\u062e\u0645\u060c \u0644\u0627\u0631\u0648\u060c \u0634\u0641\u06cc\u0631\u0647 \u0648 \u062d\u0634\u0631\u0647 \u0628\u0627\u0644\u063a \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0627\u0633\u062a. \u0628\u0631\u062e\u0644\u0627\u0641 \u0622\u0641\u062a \u0633\u0631 \u062e\u0631\u0637\u0648\u0645\u06cc \u06cc\u0648\u0646\u062c\u0647 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0628\u0644\u0648\u063a \u06a9\u0627\u0645\u0644 \u0646\u06cc\u0632 \u062e\u0633\u0627\u0631\u062a \u0641\u0631\u0627\u0648\u0627\u0646\u06cc \u0648\u0627\u0631\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n\n\n\n<p>\u0633\u0631\u0639\u062a \u062a\u06a9\u062b\u06cc\u0631 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f \u0627\u0633\u062a \u0648 \u0628\u0647\u200c\u0633\u0631\u0639\u062a \u067e\u062e\u0634 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0644\u06cc\u0644 \u0622\u0646 \u062f\u0648 \u0686\u06cc\u0632 \u0627\u0633\u062a. \u062d\u0634\u0631\u0627\u062a \u0645\u0627\u062f\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0647\u0631 \u0646\u0648\u0628\u062a \u062a\u062e\u0645\u200c\u0631\u06cc\u0632\u06cc \u062f\u0631 \u062d\u062f\u0648\u062f \u06f3\u06f0\u06f0-\u06f5\u06f0\u06f0 \u062a\u062e\u0645 \u0628\u06af\u0632\u0627\u0631\u0646\u062f.<\/p>\n\n\n\n<p>\u0627\u06af\u0631 \u062a\u0639\u062f\u0627\u062f \u0627\u06cc\u0646 \u062d\u0634\u0631\u0627\u062a \u0647\u0645 \u0628\u0647 \u06f5\u06f0 \u0639\u062f\u062f \u062f\u0631 \u0645\u062a\u0631\u0645\u0631\u0628\u0639 \u0628\u0631\u0633\u062f \u0647\u0645\u06cc\u0646 \u062a\u0639\u062f\u0627\u062f \u062a\u062e\u0645 \u06a9\u0627\u0641\u06cc \u0627\u0633\u062a \u062a\u0627 \u06cc\u06a9 \u062f\u0631\u062e\u062a \u0646\u062e\u0644 \u0631\u0627 \u0646\u0627\u0628\u0648\u062f \u06a9\u0646\u062f.<\/p>\n\n\n\n<p>\u0627\u0632 \u0637\u0631\u0641 \u062f\u06cc\u06af\u0631 \u062d\u0634\u0631\u0647 \u0628\u0627\u0644\u063a \u0642\u062f\u0631\u062a \u067e\u0631\u0648\u0627\u0632 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631\u0647\u0627 \u067e\u0631\u0648\u0627\u0632 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u062f\u0648 \u0639\u0627\u0645\u0644 \u0628\u0627\u0639\u062b \u0628\u0647\u200c\u0633\u0631\u0639\u062a \u067e\u062e\u0634 \u0634\u062f\u0646 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0648 \u062e\u0633\u0627\u0631\u062a \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0647\u0633\u062a\u0646\u062f.<\/p>\n\n\n\n<p>\u062d\u0634\u0631\u0627\u062a \u0645\u0627\u062f\u0647 \u0628\u0631\u0627\u06cc \u062a\u062e\u0645\u200c\u06af\u0630\u0627\u0631\u06cc \u0627\u063a\u0644\u0628 \u0627\u0632 \u062a\u0627\u062c \u062f\u0631\u062e\u062a \u0646\u062e\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u061b \u0627\u0645\u0627 \u0627\u0632 \u0645\u06a9\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u062f\u06cc\u06af\u0631 \u0628\u0631\u0627\u06cc \u062a\u062e\u0645\u200c\u06af\u0630\u0627\u0631\u06cc \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0646\u0642\u0637\u0647\u200c\u0647\u0627\u06cc \u0627\u062a\u0635\u0627\u0644 \u0628\u0631\u06af\u200c\u0647\u0627\u06cc \u062c\u0648\u0627\u0646 \u0628\u0647 \u0633\u0627\u0642\u0647 \u0648 \u0642\u0633\u0645\u062a\u200c\u0647\u0627\u06cc \u0632\u062e\u0645\u06cc \u062a\u0646\u0647 \u0646\u06cc\u0632 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f.<\/p>\n\n\n\n<p>\u0628\u0639\u062f \u0627\u0632 \u062e\u0627\u0631\u062c \u0634\u062f\u0646 \u0627\u0632 \u062a\u062e\u0645 \u0644\u0627\u0631\u0648 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0647 \u0633\u0645\u062a \u062f\u0627\u062e\u0644 \u062a\u0646\u0647 \u062e\u0631\u0645\u0627 \u062a\u0648\u0646\u0644 \u0645\u06cc\u200c\u0632\u0646\u062f. \u0627\u06cc\u0646 \u062a\u0648\u0646\u0644\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062a\u0627 \u06f3 \u0645\u062a\u0631 \u0637\u0648\u0644 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u062d\u0641\u0631\u0647\u200c\u0647\u0627 \u0628\u0627\u0639\u062b \u062a\u0636\u0639\u06cc\u0641 \u0648 \u062f\u0631\u0646\u0647\u0627\u06cc\u062a \u0646\u0627\u0628\u0648\u062f\u06cc \u062f\u0631\u062e\u062a \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n\n\n\n<p>\u0628\u0639\u062f \u0627\u0632 \u0627\u062a\u0645\u0627\u0645 \u062f\u0648\u0631\u0647 \u0644\u0627\u0631\u0648\u06cc \u0627\u06cc\u0646 \u062d\u0634\u0631\u0627\u062a \u0628\u0647 \u0628\u06cc\u0631\u0648\u0646 \u062f\u0631\u062e\u062a \u0628\u0631\u0645\u06cc\u200c\u06af\u0631\u062f\u0627\u0646\u062f \u0648 \u062f\u0631 \u067e\u06cc\u0644\u0647\u200c\u0647\u0627\u06cc\u06cc \u0645\u0639\u0644\u0642 \u0627\u0632 \u062f\u0631\u062e\u062a \u062a\u0628\u062f\u06cc\u0644 \u0628\u0647 \u0634\u0641\u06cc\u0631\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>&nbsp;<\/strong><strong>\u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u06cc\u0648\u0646\u062c\u0647<\/strong><\/h3>\n\n\n\n<p>\u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u06cc\u0648\u0646\u062c\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u06cc\u0646 \u062f\u0634\u0645\u0646\u0627\u0646 \u0627\u0645\u0631\u0648\u0632\u06cc \u06af\u06cc\u0627\u0647 \u06cc\u0648\u0646\u062c\u0647 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u062d\u0634\u0631\u0647 \u0646\u0627\u0642\u0644 \u0627\u06cc\u0646 \u0622\u0641\u062a \u0627\u0632 \u0628\u0631\u06af \u0648 \u0633\u0627\u0642\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061b \u0627\u0645\u0627 \u062e\u0633\u0627\u0631\u062a \u0627\u0635\u0644\u06cc \u0631\u0627 \u0644\u0627\u0631\u0648\u0647\u0627\u06cc \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0647 \u0639\u0645\u0644 \u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f.<\/p>\n\n\n\n<p>\u0644\u0627\u0631\u0648\u0647\u0627\u06cc \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u06f1 \u0648 \u06f2 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0628\u0647 \u0639\u0644\u062a \u06a9\u0648\u0686\u06a9 \u0628\u0648\u062f\u0646 \u062e\u0637\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0646\u062f\u0627\u0631\u0646\u062f \u0627\u0645\u0627 \u0644\u0627\u0631\u0648\u0647\u0627\u06cc \u0633\u0646\u06cc\u0646 \u06f3 \u0648 \u06f4 \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u062e\u0633\u0627\u0631\u062a \u0631\u0627 \u0645\u06cc\u200c\u0632\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0644\u0627\u0631\u0648\u0647\u0627 \u0628\u0647 \u062a\u063a\u0630\u06cc\u0647 \u0632\u06cc\u0627\u062f\u06cc \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f \u0648 \u062a\u0646\u0647\u0627 \u0627\u0632 \u062c\u0648\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0646\u062a\u0647\u0627\u06cc\u06cc \u062a\u063a\u0630\u06cc\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n\n\n\n<p>\u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u062a\u063a\u0630\u06cc\u0647 \u0627\u0632 \u062c\u0648\u0627\u0646\u0647 \u0627\u0646\u062a\u0647\u0627\u06cc\u06cc \u0627\u06cc\u0646 \u062d\u0634\u0631\u0627\u062a \u0628\u0627\u0639\u062b \u0642\u0637\u0639 \u0645\u0631\u06cc\u0633\u062a\u0645 \u0627\u0646\u062a\u0647\u0627\u06cc\u06cc \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0647\u0645\u06cc\u0646 \u0639\u0645\u0644 \u0628\u0627\u0639\u062b \u062a\u0648\u0642\u0641 \u0631\u0634\u062f \u06af\u06cc\u0627\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u062a\u0639\u062f\u0627\u062f \u0628\u0627\u0644\u0627 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0627\u062a\u060c \u062a\u0645\u0627\u0645\u06cc \u0628\u0631\u06af\u200c\u0647\u0627 \u062e\u0634\u06a9 \u0648 \u0646\u0627\u0628\u0648\u062f \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u062d\u0635\u0648\u0644 \u0686\u06cc\u0646 \u0627\u0648\u0644 \u0631\u0627 \u062a\u0645\u0627\u0645\u0627\u064b \u0646\u0627\u0628\u0648\u062f \u06a9\u0646\u0646\u062f.<\/p>\n\n\n\n<p>\u062f\u0631 \u0645\u0631\u062d\u0644\u0647 \u0634\u0641\u06cc\u0631\u06af\u06cc \u0622\u0641\u062a\u200c\u0632\u062f\u06af\u06cc \u062d\u0627\u062f\u060c \u0628\u0631\u06af\u200c\u0647\u0627 \u0647\u0645\u0647 \u0645\u0634\u0628\u06a9 \u0648 \u0633\u0648\u0631\u0627\u062e\u200c\u0633\u0648\u0631\u0627\u062e \u0647\u0633\u062a\u0646\u062f. \u0628\u0647 \u0639\u0644\u062a \u0631\u0646\u06af \u067e\u06cc\u0644\u0647 \u0644\u0627\u0631\u0648 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0645\u0632\u0631\u0639\u0647 \u0627\u0632 \u062f\u0648\u0631 \u0633\u0641\u06cc\u062f \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f. \u062a\u0639\u062f\u0627\u062f \u06f5\u06f0 \u0639\u062f\u062f \u0627\u0632 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0627\u062a \u062f\u0631 \u06cc\u06a9 \u0645\u062a\u0631\u0645\u0631\u0628\u0639 \u0632\u0645\u06cc\u0646\u060c \u0647\u0645\u200c\u0645\u0639\u0646\u06cc \u0628\u0627 \u0645\u0631\u06af \u0645\u0632\u0631\u0639\u0647 \u06cc\u0648\u0646\u062c\u0647 \u0627\u0633\u062a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0633\u0648\u0633\u06a9 \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc \u067e\u0633\u062a\u0647<\/h2>\n\n\n\n<p>\u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f <a href=\"https:\/\/pesterafsanjan.com\/blog\/%d8%b4%d8%ae%d9%85-%d8%b2%d8%af%d9%86-%d8%af%d8%b1%d8%ae%d8%aa-%d9%be%d8%b3%d8%aa%d9%87\">\u0634\u062e\u0645\u200c\u0632\u062f\u0646 \u0627\u0632 \u0645\u0624\u062b\u0631\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0627\u062a<\/a> \u0627\u0633\u062a. \u0628\u0627 \u0634\u062e\u0645\u200c\u0632\u0646 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u062a\u0646\u0647 \u062f\u0631\u062e\u062a\u0627\u0646\u060c \u062c\u0645\u0639\u06cc\u062a \u0622\u0646\u200c\u0647\u0627 \u0628\u0647\u200c\u0637\u0648\u0631 \u0645\u0639\u0646\u0627\u062f\u0627\u0631\u06cc \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f.<\/p>\n\n\n\n<p>\u0644\u0627\u0632\u0645 \u0628\u0647 \u0630\u06a9\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0627\u062a\u060c \u0628\u0647 \u062f\u0644\u06cc\u0644 \u067e\u0631\u0648\u0627\u0632 \u0648 \u0642\u062f\u0631\u062a \u062c\u0627\u0628\u062c\u0627\u06cc\u06cc \u0622\u0646\u200c\u0647\u0627\u060c \u0634\u062e\u0645\u200c\u0632\u0646 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0633\u0637\u062d \u0648\u0633\u06cc\u0639\u06cc \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f.<\/p>\n\n\n\n<p>\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 <a href=\"https:\/\/pesterafsanjan.com\/product-category\/%D8%B3%D9%85-%D9%82%D8%A7%D8%B1%DA%86-%DA%A9%D8%B4\/%DA%A9%D9%86%D8%AA%D8%B1%D9%84-%D8%A2%D9%81%D8%A7%D8%AA-%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C\/%DA%A9%D9%88%D8%AF\">\u0633\u0645\u0648\u0645 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc<\/a> \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc\u060c \u0627\u0628\u062a\u062f\u0627 \u0628\u0627\u06cc\u062f \u0627\u0632 \u062c\u0645\u0639\u06cc\u062a \u0628\u0627\u0644\u0627\u06cc \u0622\u0641\u062a \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u0634\u0648\u062f.<\/p>\n\n\n\n<p>\u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0646\u0638\u0648\u0631\u060c 100 \u0634\u0627\u062e\u0647 \u0628\u0647\u200c\u0637\u0648\u0631 \u062a\u0635\u0627\u062f\u0641\u06cc \u0628\u0631\u0631\u0633\u06cc\u200c\u0634\u062f\u0647 \u0648 \u062f\u0631\u0635\u0648\u0631\u062a\u06cc\u200c\u06a9\u0647 25 \u062a\u0627 30 \u0634\u0627\u062e\u0647 \u0627\u0632 \u0622\u0641\u062a \u0622\u0644\u0648\u062f\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0628\u0627\u06cc\u062f \u0645\u0628\u0627\u0631\u0632\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f.<\/p>\n\n\n\n<p>\u0628\u0647\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0628\u0631\u0627\u06cc \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u0622\u0641\u062a\u060c \u0627\u0632 \u062a\u0648\u0631\u0645 \u062c\u0648\u0627\u0646\u0647 \u062a\u0627 \u0642\u0628\u0644 \u0627\u0632 \u0628\u0627\u0632 \u0634\u062f\u0646 \u062c\u0648\u0627\u0646\u0647\u200c\u0647\u0627 \u0627\u0633\u062a \u0648 \u0633\u0631\u0634\u0627\u062e\u0647\u200c\u0647\u0627 \u0628\u0627\u06cc\u062f \u0647\u062f\u0641 \u0627\u0635\u0644\u06cc \u0633\u0645\u200c\u067e\u0627\u0634\u06cc \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u0646\u062f. \u0633\u0645 \u062f\u06cc\u0627\u0632\u06cc\u0646\u0648\u0646 \u0628\u0647 \u0646\u0633\u0628\u062a 1.5 \u0644\u06cc\u062a\u0631 \u062f\u0631 \u0647\u0632\u0627\u0631 \u0648 <a href=\"https:\/\/pesterafsanjan.com\/product-category?s=%D9%88%D9%84%DA%A9\">\u062f\u0631 \u0635\u0648\u0631\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 1 \u062a\u0627 2 \u0644\u06cc\u062a\u0631 \u0631\u0648\u063a\u0646 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u0633\u0645\u060c \u062f\u0648\u0627\u0645 \u0633\u0645 \u0627\u0641\u0632\u0648\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><div style=\"display: flex; justify-content:center; flex-wrap:wrap; border-bottom:1px solid #f7f7f7; border-left:1px solid #f7f7f7; margin-bottom:20px\"><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/800\/\u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc-12_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc 25 \u06a9\u06cc\u0644\u0648\u06cc\u06cc\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc 25 \u06a9\u06cc\u0644\u0648\u06cc\u06cc<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0648\u067e\u062a\u0627\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">4,700,000 \u062a\u0648\u0645\u0627\u0646<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f-\u067e\u0633\u062a\u0647\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/716\/1 (7)_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc \u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f \u067e\u0633\u062a\u0647 20 \u0644\u06cc\u062a\u0631\u06cc\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f-\u067e\u0633\u062a\u0647\">\u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc \u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f \u067e\u0633\u062a\u0647 20 \u0644\u06cc\u062a\u0631\u06cc<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f-\u067e\u0633\u062a\u0647\"><span style=\"text-decoration:line-through; color: red; margin-right:10px;\">3,700,000 \u062a\u0648\u0645\u0627\u0646<\/span><span style=\"margin-left:5px;\">3,500,000 \u062a\u0648\u0645\u0627\u0646<\/span><\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/753\/\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc-1_350x350.webp\" alt=\"\u06a9\u0648\u062f \u0647\u06cc\u0648\u0645\u06cc\u06a9 \u0627\u0633\u06cc\u062f \u0645\u0627\u06cc\u0639 \u0628\u06cc\u0648 \u0627\u06af\u0631\u06cc 20 \u0644\u06cc\u062a\u0631\u06cc\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u0647\u06cc\u0648\u0645\u06cc\u06a9 \u0627\u0633\u06cc\u062f \u0645\u0627\u06cc\u0639 \u0628\u06cc\u0648 \u0627\u06af\u0631\u06cc 20 \u0644\u06cc\u062a\u0631\u06cc<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0647\u06cc\u0648\u0645\u06cc\u06a9-\u0627\u0633\u06cc\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/799\/544_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc 20 \u0644\u06cc\u062a\u0631\u06cc (\u06af\u0648\u06af\u0631\u062f \u0645\u0627\u06cc\u0639 \u06a9\u0644\u0633\u06cc\u0645\u06cc)\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc 20 \u0644\u06cc\u062a\u0631\u06cc (\u06af\u0648\u06af\u0631\u062f \u0645\u0627\u06cc\u0639 \u06a9\u0644\u0633\u06cc\u0645\u06cc)<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0648\u0645\u06cc\u06a9\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">1,950,000 \u062a\u0648\u0645\u0627\u0646<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0645\u06cc\u06a9\u0631\u0648-\u0645\u06cc\u06a9\u0633-\u067e\u0648\u062f\u0631\u06cc-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/798\/\u0645\u06cc\u06a9\u0631\u0648\u0645\u06cc\u06a9\u0633-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc12_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0645\u06cc\u06a9\u0631\u0648\u0645\u06cc\u06a9\u0633 \u067e\u0648\u062f\u0631\u06cc \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0645\u06cc\u06a9\u0631\u0648-\u0645\u06cc\u06a9\u0633-\u067e\u0648\u062f\u0631\u06cc-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u0645\u06cc\u06a9\u0631\u0648\u0645\u06cc\u06a9\u0633 \u067e\u0648\u062f\u0631\u06cc \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0645\u06cc\u06a9\u0631\u0648-\u0645\u06cc\u06a9\u0633-\u067e\u0648\u062f\u0631\u06cc-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0645\u06cc\u06a9\u0631\u0648-\u0645\u06cc\u06a9\u0633-\u067e\u0648\u062f\u0631\u06cc-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f-\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0642\u0627\u0631\u0686-\u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/818\/\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f-\u0628\u0627\u06a9\u062a\u0648\u0644\u0646\u062f_350x350.jpg\" alt=\"\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f \u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc (\u0642\u0627\u0631\u0686 \u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627)\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f-\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0642\u0627\u0631\u0686-\u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627\">\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f \u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc (\u0642\u0627\u0631\u0686 \u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627)<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u0645\u0627\u06cc\u06a9\u0648\u0644\u0646\u062f-\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0642\u0627\u0631\u0686-\u0645\u0627\u06cc\u06a9\u0648\u0631\u06cc\u0632\u0627\">200,000 \u062a\u0648\u0645\u0627\u0646<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9\u0644\u0633\u06cc\u0645\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/45\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9-1\u0644\u0633\u06cc\u0645_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0646\u06cc\u062a\u0631\u0627\u062a \u06a9\u0644\u0633\u06cc\u0645\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9\u0644\u0633\u06cc\u0645\">\u06a9\u0648\u062f \u0646\u06cc\u062a\u0631\u0627\u062a \u06a9\u0644\u0633\u06cc\u0645<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9\u0644\u0633\u06cc\u0645\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0646\u06cc\u062a\u0631\u0627\u062a-\u06a9\u0644\u0633\u06cc\u0645\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0647\u0648\u06a9\u0631\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/37\/\u0647\u0648\u06a9\u0631-1_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc \u0647\u0648\u06a9\u0631\"><\/a><a style=\"font-size:15px; display:block; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0647\u0648\u06a9\u0631\">\u06a9\u0648\u062f \u0632\u06cc\u0633\u062a\u06cc \u0647\u0648\u06a9\u0631<\/a><a style=\"font-size:16px; display:block; color:#008000; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0632\u06cc\u0633\u062a\u06cc-\u0647\u0648\u06a9\u0631\">1,000,000 \u062a\u0648\u0645\u0627\u0646<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06af\u0648\u06af\u0631\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/634\/987465132_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u06af\u0648\u06af\u0631\u062f \u0645\u0627\u06cc\u0639 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06af\u0648\u06af\u0631\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u06a9\u0648\u062f \u06af\u0648\u06af\u0631\u062f \u0645\u0627\u06cc\u0639 \u0628\u06cc\u0648\u0627\u06af\u0631\u06cc<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06af\u0648\u06af\u0631\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06af\u0648\u06af\u0631\u062f-\u0645\u0627\u06cc\u0639-\u0628\u06cc\u0648\u0627\u06af\u0631\u06cc\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-\u0633\u0627\u0632\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/743\/\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-11_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0633\u0648\u0644\u0641\u0627\u062a \u0622\u0647\u0646 \u06a9\u0646\u062c\u0627\u0644\u0647 \u0633\u0627\u0632\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-\u0633\u0627\u0632\">\u06a9\u0648\u062f \u0633\u0648\u0644\u0641\u0627\u062a \u0622\u0647\u0646 \u06a9\u0646\u062c\u0627\u0644\u0647 \u0633\u0627\u0632<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-\u0633\u0627\u0632\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0633\u0648\u0644\u0641\u0627\u062a-\u0622\u0647\u0646-\u06a9\u0646\u062c\u0627\u0644\u0647-\u0633\u0627\u0632\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u06a9\u0644\u0627\u062a-\u0622\u0647\u0646-6-\u0631\u0648\u06cc\u0634\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/594\/1-(225)_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u06a9\u0644\u0627\u062a \u0622\u0647\u0646 (6%) \u0631\u0648\u06cc\u0634\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u06a9\u0644\u0627\u062a-\u0622\u0647\u0646-6-\u0631\u0648\u06cc\u0634\">\u06a9\u0648\u062f \u06a9\u0644\u0627\u062a \u0622\u0647\u0646 (6%) \u0631\u0648\u06cc\u0634<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u06a9\u0644\u0627\u062a-\u0622\u0647\u0646-6-\u0631\u0648\u06cc\u0634\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u06a9\u0644\u0627\u062a-\u0622\u0647\u0646-6-\u0631\u0648\u06cc\u0634\">09916924189<\/a><\/div><div style=\"display:flex; flex-direction:column; flex-grow:1; width:25%; padding:8px; border-top:1px solid #f7f7f7; border-right:1px solid #f7f7f7; min-width:120px; align-items:center\"><a href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\"><img decoding=\"async\" src=\"https:\/\/pesterafsanjan.com\/images\/products\/product\/702\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc2_350x350.jpg\" alt=\"\u06a9\u0648\u062f \u0641\u0633\u0641\u06cc\u062a \u067e\u062a\u0627\u0633\u06cc\u0645 \u0641\u0648\u06af\u0627\u0631\u062f \u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\"><\/a><a style=\"font-size:15px; display:block; flex-grow:1; text-align:center\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\">\u06a9\u0648\u062f \u0641\u0633\u0641\u06cc\u062a \u067e\u062a\u0627\u0633\u06cc\u0645 \u0641\u0648\u06af\u0627\u0631\u062f \u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc<\/a><a style=\"font-size:16px; display:block; color:#28a745; margin-top:15px;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\">\u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f<\/a><a style=\"font-size:16px; display:block; color:#dc3545;\" href=\"https:\/\/pesterafsanjan.com\/product\/\u06a9\u0648\u062f-\u0641\u0633\u0641\u06cc\u062a-\u067e\u062a\u0627\u0633\u06cc\u0645-\u0641\u0648\u06af\u0627\u0631\u062f-\u0622\u0631\u06cc\u0627\u0634\u06cc\u0645\u06cc\">09916924189<\/a><\/div><\/div><a href=\"https:\/\/pesterafsanjan.com\/shop\" style=\"display:block; text-align:center; background-color:#9C27B0; color: #fff; padding:10px; font-size:15px; font-family:IRANSansWeb_Light; margin:30px 0;\">\u0645\u0634\u0627\u0647\u062f\u0647 \u062a\u0645\u0627\u0645\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0641\u0631\u0648\u0634\u06af\u0627\u0647<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>\u0628\u0631\u0627\u06cc \u0639\u0636\u0648\u06cc\u062a \u062f\u0631 \u06a9\u0627\u0646\u0627\u0644 \u062a\u0644\u06af\u0631\u0627\u0645\u060c \u0627\u06cc\u0646\u0633\u062a\u0627\u06af\u0631\u0627\u0645 \u0648 \u0622\u067e\u0627\u0631\u0627\u062a \u067e\u0633\u062a\u0647 \u0631\u0641\u0633\u0646\u062c\u0627\u0646 \u0628\u0631 \u0631\u0648\u06cc \u062a\u0635\u0627\u0648\u06cc\u0631 \u0632\u06cc\u0631 \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f:<\/strong><\/p>\n\n\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0622\u0641\u062a \u0633\u0631\u062e\u0631\u0637\u0648\u0645\u06cc\u060c \u0647\u0645\u0627\u0646\u200c\u0637\u0648\u0631 \u06a9\u0647 \u0627\u0632 \u0627\u0633\u0645\u0634 \u067e\u06cc\u062f\u0627\u0633\u062a \u062d\u0634\u0631\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u062d\u0645\u0644\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06af\u0633\u062a\u0631\u0647\u200c\u06cc \u0628\u0632\u0631\u06af\u06cc \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0631\u0627 \u0645\u0648\u0631\u062f \u0647\u062c\u0648\u0645 \u0642\u0631\u0627\u0631 \u0628\u062f\u0647\u062f. \u063a\u0644\u0627\u062a\u060c \u0633\u0628\u0632\u06cc\u200c\u0647\u0627\u060c \u0635\u06cc\u0641\u06cc\u200c\u062c\u0627\u062a \u0648 \u062d\u062a\u06cc \u0628\u0639\u0636\u06cc \u0627\u0632 \u0645\u06cc\u0648\u0647\u200c\u0647\u0627 \u0646\u06cc\u0632 \u0627\u0632 \u0627\u06cc\u0646 \u062d\u0634\u0631\u0647 \u062f\u0631 \u0627\u0645\u0627\u0646 \u0646\u06cc\u0633\u062a\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0627\u0632 \u0645\u062c\u0644\u0647 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u067e\u0633\u062a\u0647 \u0631\u0641\u0633\u0646\u062c\u0627\u0646\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0622\u0641\u062a \u0633\u0648\u0633\u06a9 [&hellip;]<\/p>\n","protected":false},"author":118,"featured_media":78611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[233,15884],"tags":[24793,256],"class_list":["post-10671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-233","category-15884","tag-24793","tag-256"],"acf":[],"_links":{"self":[{"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/posts\/10671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/users\/118"}],"replies":[{"embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/comments?post=10671"}],"version-history":[{"count":3,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/posts\/10671\/revisions"}],"predecessor-version":[{"id":94444,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/posts\/10671\/revisions\/94444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/media\/78611"}],"wp:attachment":[{"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/media?parent=10671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/categories?post=10671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pesterafsanjan.com\/blog\/wp-json\/wp\/v2\/tags?post=10671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}